{"id":1334,"count":8,"description":"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.","link":"https:\/\/zfl-lernen.de\/en\/lernmodule\/nachhaltigkeit\/","name":"Nachhaltigkeit","slug":"nachhaltigkeit","taxonomy":"course_category","parent":0,"meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachhaltigkeit Archive - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/nachhaltigkeit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltigkeit Archive - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/nachhaltigkeit\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/nachhaltigkeit\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/nachhaltigkeit\\\/\",\"name\":\"Nachhaltigkeit Archive - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"description\":\"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/nachhaltigkeit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/nachhaltigkeit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltigkeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltigkeit Archive - ZfL Lernen","description":"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/lernmodule\/nachhaltigkeit\/","og_locale":"en_US","og_type":"article","og_title":"Nachhaltigkeit Archive - ZfL Lernen","og_description":"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.","og_url":"https:\/\/zfl-lernen.de\/en\/lernmodule\/nachhaltigkeit\/","og_site_name":"ZfL Lernen","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zfl-lernen.de\/lernmodule\/nachhaltigkeit\/","url":"https:\/\/zfl-lernen.de\/lernmodule\/nachhaltigkeit\/","name":"Nachhaltigkeit Archive - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"description":"Diese Kategorie zeigt Lernmodule zum Thema Nachhaltigkeit. Die Kategorie kann Sammlungen von zusammenh\u00e4ngenden Lernmodulen oder einzelne Lernmodule enthalten.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/nachhaltigkeit\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/lernmodule\/nachhaltigkeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Nachhaltigkeit"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_category\/1334","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_category"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/taxonomies\/course_category"}],"wp:post_type":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course?course_category=1334"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}