{"id":23961,"date":"2020-03-30T12:29:21","date_gmt":"2020-03-30T10:29:21","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=lp_course&#038;p=23961"},"modified":"2024-12-20T13:37:16","modified_gmt":"2024-12-20T12:37:16","slug":"grundlagen-der-inklusion","status":"publish","type":"lp_course","link":"https:\/\/zfl-lernen.de\/en\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/","title":{"rendered":"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten"},"content":{"rendered":"<p>Zielgruppe dieses Lernmoduls sind prim\u00e4r Freiwilligendienstleistende einer F\u00f6rderschule, jedoch ist das Lernmodul selbstverst\u00e4ndlich auch f\u00fcr alle anderen Interessierten ge\u00f6ffnet.<\/p>\n<p>Vermittelt werden grundlegende Inhalte zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.<br \/>\nDie zugrundeliegenden Fragen sind:<\/p>\n<ul>\n<li>Was ist eigentlich Behinderung?<\/li>\n<li>Was ist Inklusion?<\/li>\n<li>Wie funktioniert Inklusion in der Schule?<\/li>\n<\/ul>\n<p>Bei Fragen und Anregungen wenden Sie sich gerne an das Team Digitale Lehre (zfl-digitalelehre@uni-koeln.de).<\/p>\n<p>Rufen Sie das Lernmodul \u00fcber die rechte Navigation auf.<\/p>\n<p>Viel Spa\u00df!<\/p>","protected":false},"excerpt":{"rendered":"<p>Zielgruppe dieses Lernmoduls sind prim\u00e4r Freiwilligendienstleistende einer F\u00f6rderschule, jedoch ist das Lernmodul selbstverst\u00e4ndlich auch f\u00fcr alle anderen Interessierten ge\u00f6ffnet. Vermittelt werden grundlegende Inhalte zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem. Die zugrundeliegenden Fragen sind: Was ist eigentlich Behinderung? &hellip; <\/p>","protected":false},"author":4,"featured_media":36692,"comment_status":"closed","ping_status":"closed","template":"","kooperation":[203,1249],"licence":[579],"mitwirkende":[584],"course_category":[591,1196],"course_tag":[1003,563,562,559,1005,558,1004,560,561],"class_list":["post-23961","lp_course","type-lp_course","status-publish","has-post-thumbnail","hentry","kooperation-digill","kooperation-paedagogik-und-rehabilitation","licence-cc-by-sa-4-0","mitwirkende-annika-bussmann","course_category-diversitaet","course_category-sonderpaedagogische-bildungsmaterialien","course_tag-behinderung","course_tag-bildungsgerechtigkeit","course_tag-diversity","course_tag-foerderschule","course_tag-freiwilligendienst","course_tag-inklusion","course_tag-inklusive-kontexte","course_tag-sonderpaedagogik","course_tag-sonderpaedagogische-grundlagen","course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grundlagen der Inklusion\" \/>\n<meta property=\"og:description\" content=\"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T12:37:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Inkusion.png\" \/>\n\t<meta property=\"og:image:width\" content=\"507\" \/>\n\t<meta property=\"og:image:height\" content=\"289\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Grundlagen der Inklusion\" \/>\n<meta name=\"twitter:description\" content=\"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Inkusion.png\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/\",\"name\":\"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL_C_LM_Inklusion-1.jpg\",\"datePublished\":\"2020-03-30T10:29:21+00:00\",\"dateModified\":\"2024-12-20T12:37:16+00:00\",\"description\":\"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL_C_LM_Inklusion-1.jpg\",\"contentUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL_C_LM_Inklusion-1.jpg\",\"width\":1200,\"height\":800,\"caption\":\"Foto: Andi Wiland | gesellschaftsbilder.de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/diversitaet\\\/grundlagen-der-inklusion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten - ZfL Lernen","description":"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/","og_locale":"en_US","og_type":"article","og_title":"Grundlagen der Inklusion","og_description":"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.","og_url":"https:\/\/zfl-lernen.de\/en\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2024-12-20T12:37:16+00:00","og_image":[{"width":507,"height":289,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Inkusion.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_title":"Grundlagen der Inklusion","twitter_description":"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.","twitter_image":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Inkusion.png","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/","url":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/","name":"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/#primaryimage"},"image":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/#primaryimage"},"thumbnailUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_C_LM_Inklusion-1.jpg","datePublished":"2020-03-30T10:29:21+00:00","dateModified":"2024-12-20T12:37:16+00:00","description":"Dieses Lernmodul vermittelt Grundlagen zu Behinderung, Inklusion sowie inklusiver Bildung im deutschen Schulsystem.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/#primaryimage","url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_C_LM_Inklusion-1.jpg","contentUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_C_LM_Inklusion-1.jpg","width":1200,"height":800,"caption":"Foto: Andi Wiland | gesellschaftsbilder.de"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/lernmodule\/diversitaet\/grundlagen-der-inklusion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Kurse","item":"https:\/\/zfl-lernen.de\/courses\/"},{"@type":"ListItem","position":3,"name":"Grundlagen der Inklusion in sonderp\u00e4dagogischen Kontexten"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/23961","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/lp_course"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/comments?post=23961"}],"version-history":[{"count":5,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/23961\/revisions"}],"predecessor-version":[{"id":81873,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/23961\/revisions\/81873"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media\/36692"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=23961"}],"wp:term":[{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=23961"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=23961"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=23961"},{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_category?post=23961"},{"taxonomy":"course_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_tag?post=23961"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}