{"id":37480,"date":"2020-12-04T19:17:00","date_gmt":"2020-12-04T18:17:00","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=lp_course&#038;p=37480"},"modified":"2024-12-20T13:18:54","modified_gmt":"2024-12-20T12:18:54","slug":"facharbeit-schreiben-3","status":"publish","type":"lp_course","link":"https:\/\/zfl-lernen.de\/en\/lernmodule\/methoden\/facharbeit-schreiben-3\/","title":{"rendered":"Facharbeiten: 3. Gliedern und Strukturieren"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">In dem Lernmodul <\/span><b>&#8222;Gliedern und Strukturieren&#8220;<\/b><span style=\"font-weight: 400;\"> zeigen wir Ihnen, wie Sie Ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.<\/span><\/p>\n<p>Rufen Sie das Lernmodul \u00fcber die rechte Navigation auf.<\/p>","protected":false},"excerpt":{"rendered":"<p>In dem Lernmodul &#8222;Gliedern und Strukturieren&#8220; zeigen wir Ihnen, wie Sie Ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen. Rufen Sie das Lernmodul \u00fcber die rechte Navigation auf.<\/p>","protected":false},"author":57,"featured_media":36298,"comment_status":"closed","ping_status":"closed","template":"","kooperation":[203,578,754],"licence":[579],"mitwirkende":[605,690,689],"course_category":[1200,594],"course_tag":[891,956,959,958,957],"class_list":["post-37480","lp_course","type-lp_course","status-publish","has-post-thumbnail","hentry","kooperation-digill","kooperation-hans-riegel","kooperation-professionalisierung-sprachlicher-kompetenzen","licence-cc-by-sa-4-0","mitwirkende-aimee-platte","mitwirkende-natascha-streit","mitwirkende-prof-in-dr-kirsten-schindler","course_category-facharbeit-schreiben","course_category-methoden","course_tag-facharbeit","course_tag-gliedern","course_tag-schuelerinnen","course_tag-sek-i","course_tag-strukturieren","course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Facharbeiten: 3. Gliedern und Strukturieren - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/methoden\/facharbeit-schreiben-3\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Facharbeit schreiben - Gliedern und strukturieren\" \/>\n<meta property=\"og:description\" content=\"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/methoden\/facharbeit-schreiben-3\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-20T12:18:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Facharbeit schreiben - Gliedern und strukturieren\" \/>\n<meta name=\"twitter:description\" content=\"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/\",\"name\":\"Facharbeiten: 3. Gliedern und Strukturieren - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL-LM_wissenschaftliches_Formulieren.jpg\",\"datePublished\":\"2020-12-04T18:17:00+00:00\",\"dateModified\":\"2024-12-20T12:18:54+00:00\",\"description\":\"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL-LM_wissenschaftliches_Formulieren.jpg\",\"contentUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ZfL-LM_wissenschaftliches_Formulieren.jpg\",\"width\":1500,\"height\":1000,\"caption\":\"Foto: Pexles von Andrea Piacquadio\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/methoden\\\/facharbeit-schreiben-3\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Facharbeiten: 3. Gliedern und Strukturieren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Facharbeiten: 3. Gliedern und Strukturieren - ZfL Lernen","description":"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/lernmodule\/methoden\/facharbeit-schreiben-3\/","og_locale":"en_US","og_type":"article","og_title":"Facharbeit schreiben - Gliedern und strukturieren","og_description":"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.","og_url":"https:\/\/zfl-lernen.de\/en\/lernmodule\/methoden\/facharbeit-schreiben-3\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2024-12-20T12:18:54+00:00","og_image":[{"width":1500,"height":1000,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Facharbeit schreiben - Gliedern und strukturieren","twitter_description":"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.","twitter_image":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/","url":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/","name":"Facharbeiten: 3. Gliedern und Strukturieren - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/#primaryimage"},"image":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/#primaryimage"},"thumbnailUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg","datePublished":"2020-12-04T18:17:00+00:00","dateModified":"2024-12-20T12:18:54+00:00","description":"Dieses Lernmodul richtet sich an Sch\u00fcler*innen der SEK I und zeigt, wie sie ihre Facharbeit erfolgreich gliedern und strukturieren k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/#primaryimage","url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg","contentUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL-LM_wissenschaftliches_Formulieren.jpg","width":1500,"height":1000,"caption":"Foto: Pexles von Andrea Piacquadio"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/lernmodule\/methoden\/facharbeit-schreiben-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Kurse","item":"https:\/\/zfl-lernen.de\/courses\/"},{"@type":"ListItem","position":3,"name":"Facharbeiten: 3. Gliedern und Strukturieren"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/37480","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/lp_course"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/57"}],"replies":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/comments?post=37480"}],"version-history":[{"count":5,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/37480\/revisions"}],"predecessor-version":[{"id":81849,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/37480\/revisions\/81849"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media\/36298"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=37480"}],"wp:term":[{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=37480"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=37480"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=37480"},{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_category?post=37480"},{"taxonomy":"course_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_tag?post=37480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}