{"id":64802,"date":"2023-04-03T16:11:23","date_gmt":"2023-04-03T14:11:23","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=lp_course&#038;p=64802"},"modified":"2026-01-12T08:13:10","modified_gmt":"2026-01-12T07:13:10","slug":"ki-in-der-bildung-einfuehrung","status":"publish","type":"lp_course","link":"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/","title":{"rendered":"KI in der Bildung &#8211; eine Einf\u00fchrung"},"content":{"rendered":"<p>Herzlich Willkommen zum Lernmodul &#8222;<span style=\"color: #000000;\"><strong>KI in der Bildung &#8211; eine Einf\u00fchrung<\/strong>&#8222;.<\/span> In diesem Lernmodul erfahren Sie die Grundlagen von K\u00fcnstlicher Intelligenz (KI) in der Schule.<\/p>\n<p>Das separate Lernmodul &#8222;<a href=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-anwendungsbeispiele\/\" target=\"_blank\" rel=\"noopener\"><strong>KI in der Bildung &#8211; Anwendungsbeispiele<\/strong><\/a>&#8220; dreht sich um Einsatzm\u00f6glichkeiten und Chancen und Grenzen von KI f\u00fcr Lehrende oder Lernende. Auch Einf\u00fchrungsbeispiele lassen sich in diesem Modul finden. Sie k\u00f6nnen die Lernmodule nacheinander oder getrennt aufrufen.<\/p>\n<p>Rufen Sie das Lernmodul \u00fcber die rechte Navigation auf.<\/p>","protected":false},"excerpt":{"rendered":"<p>Herzlich Willkommen zum Lernmodul &#8222;KI in der Bildung &#8211; eine Einf\u00fchrung&#8222;. In diesem Lernmodul erfahren Sie die Grundlagen von K\u00fcnstlicher Intelligenz (KI) in der Schule. Das separate Lernmodul &#8222;KI in der Bildung &#8211; Anwendungsbeispiele&#8220; dreht sich um Einsatzm\u00f6glichkeiten und Chancen &hellip; <\/p>","protected":false},"author":4,"featured_media":67600,"comment_status":"closed","ping_status":"closed","template":"","kooperation":[203],"licence":[579],"mitwirkende":[587],"course_category":[1195,1266],"course_tag":[1181,1184,1182,1183,875],"class_list":["post-64802","lp_course","type-lp_course","status-publish","has-post-thumbnail","hentry","kooperation-digill","licence-cc-by-sa-4-0","mitwirkende-mechthild-wiesmann","course_category-digitalitaet","course_category-ki-in-der-bildung","course_tag-chatgpt","course_tag-einfuehrung","course_tag-ki","course_tag-kuenstliche-intelligenz","course_tag-schule","course"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>KI in der Bildung - eine Einf\u00fchrung - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Grundlagen zu KI\" \/>\n<meta property=\"og:description\" content=\"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-12T07:13:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Grundlagen zu KI\" \/>\n<meta name=\"twitter:description\" content=\"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/\",\"name\":\"KI in der Bildung - eine Einf\u00fchrung - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Foto-von-Tara-Winstead-scaled.jpg\",\"datePublished\":\"2023-04-03T14:11:23+00:00\",\"dateModified\":\"2026-01-12T07:13:10+00:00\",\"description\":\"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Foto-von-Tara-Winstead-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Foto-von-Tara-Winstead-scaled.jpg\",\"width\":2560,\"height\":1707,\"caption\":\"Foto von Tara Winstead\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/lernmodule\\\/digitalitaet\\\/ki-in-der-bildung-einfuehrung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/courses\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"KI in der Bildung &#8211; eine Einf\u00fchrung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"KI in der Bildung - eine Einf\u00fchrung - ZfL Lernen","description":"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/","og_locale":"en_US","og_type":"article","og_title":"Grundlagen zu KI","og_description":"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.","og_url":"https:\/\/zfl-lernen.de\/en\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2026-01-12T07:13:10+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Grundlagen zu KI","twitter_description":"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.","twitter_image":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/","url":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/","name":"KI in der Bildung - eine Einf\u00fchrung - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/#primaryimage"},"image":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/#primaryimage"},"thumbnailUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg","datePublished":"2023-04-03T14:11:23+00:00","dateModified":"2026-01-12T07:13:10+00:00","description":"Dieses Lernmodul bietet eine Einf\u00fchrung in K\u00fcnstliche Intelligenz (KI) in der Schule am Beispiel von ChatGPT.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/#primaryimage","url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg","contentUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Foto-von-Tara-Winstead-scaled.jpg","width":2560,"height":1707,"caption":"Foto von Tara Winstead"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/lernmodule\/digitalitaet\/ki-in-der-bildung-einfuehrung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Kurse","item":"https:\/\/zfl-lernen.de\/courses\/"},{"@type":"ListItem","position":3,"name":"KI in der Bildung &#8211; eine Einf\u00fchrung"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/64802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/lp_course"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/comments?post=64802"}],"version-history":[{"count":5,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/64802\/revisions"}],"predecessor-version":[{"id":81722,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/lp_course\/64802\/revisions\/81722"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media\/67600"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=64802"}],"wp:term":[{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=64802"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=64802"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=64802"},{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_category?post=64802"},{"taxonomy":"course_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/course_tag?post=64802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}