{"id":32329,"date":"2020-08-27T14:12:43","date_gmt":"2020-08-27T12:12:43","guid":{"rendered":"https:\/\/zfl-lernen.de\/?page_id=32329"},"modified":"2023-12-19T08:00:32","modified_gmt":"2023-12-19T07:00:32","slug":"meine-schuelerinnen","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/","title":{"rendered":"Digitalisierung &#038; meine Sch\u00fcler*innen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Digitalisierung &amp; meine Sch\u00fcler*innen<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img decoding=\"async\" class=\"vc_single_image-img \" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/brooke-cagle-uHVRvDr7pg-unsplash-scaled-200x200.jpg\" width=\"200\" height=\"200\" alt=\"Ein Mann und drei Frauen unterhalten sich\" title=\"brooke-cagle--uHVRvDr7pg-unsplash\" loading=\"lazy\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><em><span style=\"font-size: small;\">Foto von Brooke Cagle von Unsplash<\/span><\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Die beinah unbegrenzten <strong>M\u00f6glichkeiten digitaler Medien<\/strong> stellen Lehrkr\u00e4fte an Schulen vor gro\u00dfe Herausforderungen: Vorbereitung und Durchf\u00fchrung zeitgem\u00e4\u00dfen Unterrichts in einer digitalen Landschaft unterscheidet sich zum Teil erheblich von den herk\u00f6mmlichen analogen Unterrichtskonzeptionen zur Wissensvermittlung. Die hohe Aktualit\u00e4t dieser Herausforderungen wird sowohl durch zahlreiche Studien als auch durch Kompetenzanforderungen der Lehrer*innenausbildung und -fortbildung belegt.<\/p>\n<p>Im Mittelpunkt steht dabei h\u00e4ufig die Frage nach der F\u00f6rderung &#8222;neuer&#8220; Kompetenzen unserer Sch\u00fcler*innen. Wo finde ich diese, was \u00e4ndert sich und was ben\u00f6tigen meine Sch\u00fcler*innen f\u00fcr ihre Zukunft in einer digitalen Welt?<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Icon Aufgabe\" title=\"ico_aufgaben\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben-12x12.png 12w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben.png 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div  class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>Was ist eigentlich Medienkompetenz?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Ein Stichwort, das dabei immer wieder viel Aufmerksamkeit auf sich zieht, ist\u00a0<strong>Medienkompetenz<\/strong>. Was damit im Kontext von Schule sowohl f\u00fcr Sch\u00fcler*innen als auch f\u00fcr Lehrkr\u00e4fte gemeint ist, ist u.a. im\u00a0<a href=\"https:\/\/medienkompetenzrahmen.nrw\/\"><u>Medienkompetenzrahmen NRW<\/u><\/a>\u00a0festgehalten.<\/p>\n<p>Dar\u00fcber hinaus gibt es noch zahlreiche weitere Rahmenbedingungen und strukturelle Aspekte zur F\u00f6rderung von Medienkompetenz, wie z.B. die Strategie der Kultusministerkonferenz zur Bildung in der digitalen Welt. Eine \u00dcbersicht \u00fcber zentrale Dokumente haben wir in <a href=\"https:\/\/prezi.com\/view\/KyryFMgsrYR73wGvxGNc\/\">dieser interaktiven Online-Pr\u00e4sentation in dem Tool \u201ePrezi\u201d<\/a> f\u00fcr Sie zusammengefasst.<\/p>\n<p>&nbsp;<\/p>\n<p>Zudem finden sich auf der Homepage des hier vorgestellten\u00a0<a href=\"https:\/\/medienkompetenzrahmen.nrw\/\"><u>Medienkompetenzrahmen NRW<\/u><\/a> weitere Informationen und konkrete Unterrichtsideen zur F\u00f6rderung der Medienkompetenz Ihrer Sch\u00fcler*innen.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>&quot;Neue&quot; Kompetenzen f\u00fcr Sch\u00fcler*innen<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Noch bevor viele Schulen sich der Digitalisierung ausgiebig widmen konnten, kam es zu Schulschlie\u00dfungen aufgrund der Coronapandemie im Fr\u00fchjahr 2020 &#8211; und die Debatte um die Notwendigkeit digitaler Kompetenzen nahm besondere Fahrt auf. Der Umstand, dass Sch\u00fcler*innen pl\u00f6tzlich von zuhause aus lernen mussten, r\u00fcckte \u201eneue\u201d, zukunftsf\u00e4hige Formen des Lehrens und Lernens wieder st\u00e4rker in den Fokus. Debatten um digitale Ausstattung, die Entwicklung von Medienkonzepten sowie neue (digitale) Lehr- und Lernformate pr\u00e4gten sowohl den Distanz- wie auch den phasenweise stattfindenden Hybrid- oder Pr\u00e4senzunterricht.<\/p>\n<p>In der \u00f6ffentlichen Debatte wurde dabei h\u00e4ufig vernachl\u00e4ssigt, dass Sch\u00fcler*innen auch Kompetenzen ben\u00f6tigen, die \u00fcber das Bedienen und Anwenden digitaler Medien weit hinausgehen und ihnen stattdessen konkret eine Teilhabe an der digitalen Welt erm\u00f6glichen.<\/p>\n<p>Hier kommt neben den \u201e4C\u201c \/ \u201e4K\u201c (<em>communication<\/em>, <em>collaboration<\/em>, <em>critical thinking<\/em>, <em>creativity<\/em>; vgl. Fadel, Bialik &amp; Trilling, 2015; deutsche \u00dcbersetzung verf\u00fcgbar unter <a href=\"https:\/\/www.joeran.de\/wp-content\/dox\/sites\/10\/4K-Skills-Vier-Dimensionen-der-Bildung-Kap-4.pdf\"><u>https:\/\/www.joeran.de\/wp-content\/dox\/sites\/10\/4K-Skills-Vier-Dimensionen-der-Bildung-Kap-4.pdf)<\/u><\/a> auch den durch die OECD (Organisation for Economic Co-operation and Development) erg\u00e4nzten Kompetenzen <em>citizenship <\/em>und <em>character development<\/em> viel Bedeutung zu:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-37298 size-full\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png\" alt=\"Kernkompetenzen f\u00fcr Lernende des 21. Jahrhunderts: Kreativit\u00e4t, kritisches Denken, Kollaboration, Kommunikation, Citizenship, Character Development\" width=\"2418\" height=\"766\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png 2418w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05-300x95.png 300w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05-1024x324.png 1024w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05-768x243.png 768w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05-1536x487.png 1536w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05-2048x649.png 2048w\" sizes=\"auto, (max-width: 2418px) 100vw, 2418px\" \/><\/p>\n<p><em><span style=\"font-size: small;\">Erweiterte Grafik vom ZfL der Universit\u00e4t zu K\u00f6ln angelehnt an &#8222;<a href=\"https:\/\/www.joeran.de\/die-4k-skills-was-meint-kreativitaet-kritisches-denken-kollaboration-kommunikation\/\">Was die Leute f\u00fcr 4K halten \u2013 und was es wirklich ist<\/a>&#8220; von J\u00f6ran Muu\u00df-Merholz | <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/\">CC BY-SA 4.0<\/a><\/span><\/em><\/p>\n<p>\u201e<em>The knowledge world is no longer divided between specialists and generalists. A new group-let&#8217;s call them \u201cversatilists\u201d-has emerged. [&#8230;] They are capable not only of constantly adapting, but also constantly learning and growing in a fast-changing world<\/em>.\u201c (Eigene \u00dcbersetzung: \u201eDie Welt des Wissens ist nicht mehr in Spezialisten und Generalisten unterteilt. Eine neue Gruppe &#8211; nennen wir sie \u201eVersatilisten\u201c hat sich gebildet. [&#8230;] Diese sind nicht nur in der Lage, sich konstant anzupassen, sondern auch in einer sich rapide ver\u00e4ndernden Welt konstant zu lernen und zu wachsen) (<a href=\"https:\/\/web-archive.oecd.org\/2012-06-14\/61660-thecasefor21st-centurylearning.htm\"><u>http:\/\/www.oecd.org\/general\/thecasefor21st-centurylearning.htm<\/u><\/a>, letzter Zugriff am 19.12.2023).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"alignleft wp-image-31947\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben.png\" alt=\"Icons Aufgabe\" width=\"60\" height=\"60\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben.png 200w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_aufgaben-12x12.png 12w\" sizes=\"auto, (max-width: 60px) 100vw, 60px\" \/>Lesen Sie sich den Blog-Artikel &#8222;<a href=\"https:\/\/www.joeran.de\/die-4k-skills-was-meint-kreativitaet-kritisches-denken-kollaboration-kommunikation\/\">DIE 4K-SKILLS: WAS MEINT KREATIVIT\u00c4T, KRITISCHES DENKEN, KOLLABORATION, KOMMUNIKATION?<\/a>&#8220; durch und \u00fcberlegen Sie:<\/p>\n<ul>\n<li>Was tue ich bereits, um die 4K meiner Sch\u00fcler*innen zu f\u00f6rdern?<\/li>\n<li>Welche der 4K sind bei mir selbst (am wenigsten \/ am meisten) ausgepr\u00e4gt?<\/li>\n<li>Inwiefern l\u00e4sst sich die F\u00f6rderung der zus\u00e4tzlichen 2K &#8222;Citizenship&#8220; und &#8222;Character Development&#8220; in meinen Unterricht implementieren?<\/li>\n<li>Welche Bedeutung haben diese 2K f\u00fcr mich &#8211; und welche f\u00fcr die Lebenswelt meiner Sch\u00fcler*innen?<\/li>\n<\/ul>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_default vc_toggle_color_default  vc_toggle_size_md\"><div class=\"vc_toggle_title\"><h4>Reflexion: Wie bereite ich meine Sch\u00fcler*innen vor?<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Um unsere Sch\u00fcler*innen auf diese Welt des Wissens vorzubereiten, gilt es, sich als (angehende) Lehrkraft Fragen zu stellen wie:<\/p>\n<ul>\n<li>Wie k\u00f6nnen wir Sch\u00fcler*innen auf ein Leben in einer digitalisierten Gesellschaft vorbereiten?<\/li>\n<li>Welche Kompetenzen ben\u00f6tige <u>ich<\/u>, um diesen Anforderungen gerecht zu werden?<\/li>\n<li>Wie sollen wir unter den momentanen Bedingungen an Schule modernen hybriden Unterricht konzipieren?<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31949 alignleft\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_chat.png\" alt=\"Icon Chat\" width=\"60\" height=\"60\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_chat.png 200w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_chat-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_chat-12x12.png 12w\" sizes=\"auto, (max-width: 60px) 100vw, 60px\" \/>Reflektieren Sie f\u00fcr sich und tauschen Sie sich ggf. mit Kolleg*innen dar\u00fcber aus.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Digitalisierung &amp; meine Sch\u00fcler*innen Foto von Brooke Cagle von Unsplash Die beinah unbegrenzten M\u00f6glichkeiten digitaler Medien stellen Lehrkr\u00e4fte an Schulen vor gro\u00dfe Herausforderungen: Vorbereitung und Durchf\u00fchrung zeitgem\u00e4\u00dfen Unterrichts in einer digitalen Landschaft unterscheidet sich zum Teil erheblich von den herk\u00f6mmlichen &hellip;","protected":false},"author":4,"featured_media":0,"parent":31614,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[1056,1072,1071,827],"kooperation":[],"licence":[596],"mitwirkende":[],"class_list":["post-32329","online-kurs","type-online-kurs","status-publish","hentry","tag-digitalisierung","tag-lehrkraft","tag-medienkompetenz","tag-schuelerinnen","licence-cc-by-sa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Digitalisierung &amp; meine Sch\u00fcler*innen - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitalisierung &amp; meine Sch\u00fcler*innen - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-19T07:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/\",\"name\":\"Digitalisierung & meine Sch\u00fcler*innen - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Bildschirmfoto-2020-11-30-um-15.29.05.png\",\"datePublished\":\"2020-08-27T12:12:43+00:00\",\"dateModified\":\"2023-12-19T07:00:32+00:00\",\"description\":\"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Bildschirmfoto-2020-11-30-um-15.29.05.png\",\"contentUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/Bildschirmfoto-2020-11-30-um-15.29.05.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/meine-schuelerinnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"eTeaching Expert\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/eteaching-expert\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Digitalisierung &#038; meine Sch\u00fcler*innen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Digitalisierung & meine Sch\u00fcler*innen - ZfL Lernen","description":"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/","og_locale":"en_US","og_type":"article","og_title":"Digitalisierung & meine Sch\u00fcler*innen - ZfL Lernen","og_description":"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2023-12-19T07:00:32+00:00","og_image":[{"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/","name":"Digitalisierung & meine Sch\u00fcler*innen - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/#primaryimage"},"image":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png","datePublished":"2020-08-27T12:12:43+00:00","dateModified":"2023-12-19T07:00:32+00:00","description":"Wie kann ich als Lehrkraft meinen Sch\u00fcler*innen, im Rahmen der Digitalisierung, Medienkompetenz vermitteln?","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/#primaryimage","url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png","contentUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Bildschirmfoto-2020-11-30-um-15.29.05.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/meine-schuelerinnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"eTeaching Expert","item":"https:\/\/zfl-lernen.de\/online-kurs\/eteaching-expert\/"},{"@type":"ListItem","position":4,"name":"Digitalisierung &#038; meine Sch\u00fcler*innen"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/32329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"up":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/31614"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=32329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=32329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=32329"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=32329"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=32329"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=32329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}