{"id":36834,"date":"2020-11-17T13:39:52","date_gmt":"2020-11-17T12:39:52","guid":{"rendered":"https:\/\/zfl-lernen.de\/?page_id=36834"},"modified":"2023-12-11T11:37:24","modified_gmt":"2023-12-11T10:37:24","slug":"weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/","title":{"rendered":"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht"},"content":{"rendered":"<p>&nbsp;<\/p>\r\n\r\n\r\n\r\n<h3>Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht<\/h3>\r\n\r\n\r\n\r\n<ul class=\"wp-block-list\">\r\n<li>NRW Handreichung zur lernf\u00f6rderlichen Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht Abgerufen am 17. August 2020 von <a href=\"https:\/\/brosch\u00fcren.nrw\/distanzunterricht\/home\/#!\/Home\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/brosch\u00fcren.nrw\/distanzunterricht\/home\/#!\/Home<\/a><\/li>\r\n<li>Blume, B. Instagram. Abgerufen am 12.01.2021 von https:\/\/www.instagram.com\/tv\/CJ5nUpzKeBg\/?igshid=1a347jkq5a0jf.<\/li>\r\n<li>BW LMZ-Brosch\u00fcre &#8222;Impulse zum Unterrichten mit Videokonferenzsystemen&#8220; Abgerufen am 17. August 2020 von https:\/\/www.lmz-bw.de\/newsroom\/newsroom\/detailseite\/lmz-broschuere-zu-unterrichten-mit-videokonferenzsystemen-veroeffentlicht\/<\/li>\r\n<li>B\u00fcndnis f\u00fcr Bildung Schule Digital. Lehren und Lernen in Zeiten der Schulschlie\u00dfung Abgerufen am 17. August 2020 von <a href=\"https:\/\/www.schultransformation.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.schultransformation.de\/<\/a><\/li>\r\n<li>Casale, G., B\u00f6rnert-Ringleb, M. &amp; Hillenbrand, C. (2020). F\u00f6rdern auf Distanz? Sonderp\u00e4dagogische Unterst\u00fctzung im Lernen und in der emotional-sozialen Entwicklung w\u00e4hrend der Schulschlie\u00dfungen 2020 gem\u00e4\u00df den Regelungen der Bundesl\u00e4nder. Zeitschrift f\u00fcr Heilp\u00e4dagogik, 71, S. 254-267.<\/li>\r\n<li>Deutsche Schulakademie.\u00a0Digitales Lernforum: Lernen digital gestalten \u2013 was Preistr\u00e4gerschulen tun. Abgerufen am 03. November 2020 von<a href=\"https:\/\/www.deutsche-schulakademie.de\/unsere-themen\/lernen-in-der-digitalen-welt\" target=\"_blank\" rel=\"noreferrer noopener\"> https:\/\/www.deutsche-schulakademie.de\/unsere-themen\/lernen-in-der-digitalen-welt<\/a><\/li>\r\n<li>Dreier, R.; Krommer, A.; N\u00f6lte, B.; Schmitz, O.. Zeitgem\u00e4\u00dfe Pr\u00fcfungsformate f\u00fcr den Distanzunterricht. Abgerufen am 30. Novembeer 2020 von <a href=\"https:\/\/medium.com\/@szcgn\/zeitgem%C3%A4%C3%9Fe-pr%C3%BCfungsformate-f%C3%BCr-den-distanzunterricht-adb4a1ffda91\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/medium.com\/@szcgn\/zeitgem%C3%A4%C3%9Fe-pr%C3%BCfungsformate-f%C3%BCr-den-distanzunterricht-adb4a1ffda91<\/a><\/li>\r\n<li>Dziak-Mahler, M. (2020). \u201eDer Schulstoff muss unbedingt reduziert werden\u201c. Abgerufen am 08. M\u00e4rz 2022 von <a href=\"https:\/\/bildungspolitik.blog.rosalux.de\/files\/2020\/11\/Koelner-Bildungsexpertin-im-Interview_-%E2%80%9EDer-Schulstoff-muss-unbedingt-reduziert-werden-_-Koelner-Stadt-Anzeiger.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/bildungspolitik.blog.rosalux.de\/files\/2020\/11\/Koelner-Bildungsexpertin-im-Interview_-%E2%80%9EDer-Schulstoff-muss-unbedingt-reduziert-werden-_-Koelner-Stadt-Anzeiger.pdf<\/a><\/li>\r\n<li>Forum Bildung Digitalisierung. DIGITALE SCHULE ZWISCHEN \u201eUNTERRICHTSABSICHERUNG\u201c UND NEUER LERNKULTUR\u00a0 von J\u00f6ran Muu\u00df-Merholz Abgerufen am 17. August 2020 von <a href=\"https:\/\/www.forumbd.de\/blog\/digitale-schule-zwischen-unterrichtsabsicherung-und-neuer-lernkultur\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.forumbd.de\/blog\/digitale-schule-zwischen-unterrichtsabsicherung-und-neuer-lernkultur\/<\/a><\/li>\r\n<li>Kantereit, T., u.a. (2020). Hybridunterricht 101. Ein Leitfaden zum Blended Learning f\u00fcr angehende Lehrer.innen. Ein Gemeinschaftswerk aus den sozialen Netzwerken. Das gesamte Buch ist unter der freien Lizenz <a href=\"https:\/\/creativecommons.org\/licenses\/by-sa\/4.0\/\" target=\"_blank\" rel=\"noopener noreferrer\">CC-BY-SA 4.0<\/a> ver\u00f6ffentlicht. Abgerufen am 17. August 2020 von <a href=\"https:\/\/mega.nz\/file\/ftAlTQKR#22T9jZCip6p5IlGTc5lL3vVVf6OMEpiEzb9V2q9aqgg\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/mega.nz\/file\/ftAlTQKR#22T9jZCip6p5IlGTc5lL3vVVf6OMEpiEzb9V2q9aqgg<\/a><\/li>\r\n<li>Kai Kaspar, Michael Becker-Mrotzek, Sandra Hofhues, Johannes K\u00f6nig, Daniela Schmeinck (Hrsg.). Bildung, Schule, Digitalisierung. Waxmann Verlag GmbH, Mu\u0308nster 2020. Abgerufen am 26. Oktober 2020 unter: <a href=\"https:\/\/www.waxmann.com\/index.php?eID=download&amp;buchnr=4246\">https:\/\/www.waxmann.com\/index.php?eID=download&amp;buchnr=4246<\/a><\/li>\r\n<li>K\u00f6lner Online-Journal zur Lehrer*innenbildung. Wege zur digitalen Kompetenz im Spannungsfeld von Politik und Realit\u00e4t.\u00a0 <a href=\"https:\/\/journals.ub.uni-koeln.de\/index.php\/k_ON\/issue\/view\/3\">https:\/\/journals.ub.uni-koeln.de\/index.php\/k_ON\/issue\/view\/3<\/a><\/li>\r\n<li>Krommer, Axel. Didaktische Schieberegler. Oder: (Distanz-)Lernen und p\u00e4dagogische Antinomien Abgerufen am 17. August 2020 von <a href=\"https:\/\/axelkrommer.com\/2020\/07\/02\/didaktische-schieberegler-oder-distanz-lernen-und-padagogische-antinomien\/#more-1780\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/axelkrommer.com\/2020\/07\/02\/didaktische-schieberegler-oder-distanz-lernen-und-padagogische-antinomien\/#more-1780<\/a><\/li>\r\n<li>NRW Didaktische Impulse zum qualifizierten Umgang mit Distanzlernen &#8211; eine Webinarreihe Abgerufen am 17. August 2020 von https:\/\/www.pacemaker-initiative.de\/post\/webinar-reihe-distanzlernen<\/li>\r\n<li>Medienzentrum Frankfurt: Hybridunterricht. Gedanken,\u00a0Ideen, Standpunkte. Videos aus Sicht unterschiedlicher Schulformen. Angerufen am 22.10.2010 unter <a href=\"https:\/\/www.youtube.com\/playlist?list=PLH8stScLVowRccLSrzatgdaoKEaloeMZp&amp;app=desktop#menu\">https:\/\/www.youtube.com\/playlist?list=PLH8stScLVowRccLSrzatgdaoKEaloeMZp&amp;app=desktop#menu<\/a><\/li>\r\n<li>Mercator Institut. Unterricht und sprachliches Lernen digital. Ideen f\u00fcr den Einsatz digitaler Medien im Pr\u00e4senz- und Distanzunterricht Abgerufen am 17. August 2020 von <a href=\"https:\/\/www.mercator-institut-sprachfoerderung.de\/de\/publikationen\/material-fuer-die-praxis\/unterricht-und-sprachliches-lernen-digital\/\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.mercator-institut-sprachfoerderung.de\/de\/publikationen\/material-fuer-die-praxis\/unterricht-und-sprachliches-lernen-digital\/<\/a><\/li>\r\n<li>Mittelbach, Tom. Scrum in die Schule. Zeit f\u00fcr mehr Agilit\u00e4t im Unterricht. Verfasst von 17 Expert:innen von innerhalb und au\u00dferhalb der Schule. Abgerufen am 05. Oktober 2020 unter <a href=\"https:\/\/visual-books.com\/scrum-in-die-schule\/\">https:\/\/visual-books.com\/scrum-in-die-schule\/<\/a><\/li>\r\n<li>Montag Stiftung Jugend und Gesellschaft: Softwareentwicklung mit Schulen f\u00fcr Schulen &#8211; Lernlog &#8211; Digitaler Lernbegleiter, Abgerufen am 17. August 2020 von <a href=\"https:\/\/www.montag-stiftungen.de\/lernlog?s=09\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.montag-stiftungen.de\/lernlog?s=09<\/a><\/li>\r\n<li>Muu\u00df-Merholz, J\u00f6ran.\u00a0 Routenplaner digitale Bildung. Inklusive Wimmelbild zum Inhalt als Poster. Abgerufen am 26.10.2020 von: <a title=\"Alle Artikel von J\u00f6ran Muu\u00df-Merholz\" href=\"https:\/\/www.joeran.de\/author\/joeran\/\">https:\/\/www.joeran.de\/buch-routenplaner-digitale-bildung-zum-freien-download-pdf\/?fbclid=IwAR2cfr-sQKrUbaM_CZOxh4i9ZO3_hX2S-cyZO0WNcelCfh9We-4NB_VvXb8<\/a><\/li>\r\n<li>Nobel, K., Barwasser, A., Melzer, C. &amp; Gr\u00fcnke, M. (2020). Webbasiertes Distanzlernen &#8211; Erfahrungen im Rahmen einer Pilotstudie w\u00e4hrend der Covid-19-Schulschlie\u00dfungen. Zeitschrift f\u00fcr Heilp\u00e4dagogik, 71, S. 465-479.<\/li>\r\n<li>schule-in-der-digitalen-welt.de. Abgerufen am 11. September 2020 unter: <a href=\"https:\/\/schule-in-der-digitalen-welt.de\/hybride-lernsettings-wie-fuhre-ich-die-ein\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hybride Lernsettings &#8211; wie f\u00fchre ich die ein? (Teil 1) &#8211; Schule in der digitalen Welt<\/a><\/li>\r\n<li>schule-in-der-digitalen-welt.de. Abgerufen am 11. September 2020 unter: <a href=\"https:\/\/schule-in-der-digitalen-welt.de\/hybride-lernsettings-wie-fuhre-ich-die-ein-teil-2\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hybride Lernsettings \u2013 wie f\u00fchre ich die ein? (Teil 2) &#8211; Schule in der digitalen Welt<\/a><\/li>\r\n<li>Unterrichten digital. Blended Learning \u2013 Planung von Pr\u00e4senz-, Hybrid- und Online-Unterricht im Corona-Jahr 2020. Abgerufen am 03. November 2020 unter: <a href=\"https:\/\/unterrichten.digital\/2020\/10\/25\/blended-learning-online-unterricht\/#Ziel_Ubergang_zwischen_Corona-Szenarien_moglichst_niedrigschwellig_und_nahtlos_gestalten\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/unterrichten.digital\/2020\/10\/25\/blended-learning-online-unterricht\/#Ziel_Ubergang_zwischen_Corona-Szenarien_moglichst_niedrigschwellig_und_nahtlos_gestalten<\/a><\/li>\r\n<li>Unterrichten digital. Mini-Fortbildung zum flipped-classroom. Abgerufen am 03. November 2020 unter: <a href=\"https:\/\/www.youtube.com\/watch?v=kDv9wK2ZwhA&amp;feature=youtu.be\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/www.youtube.com\/watch?v=kDv9wK2ZwhA&amp;feature=youtu.be<\/a><\/li>\r\n<\/ul>","protected":false},"excerpt":{"rendered":"<p>&nbsp; Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht NRW Handreichung zur lernf\u00f6rderlichen Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht Abgerufen am 17. August 2020 von https:\/\/brosch\u00fcren.nrw\/distanzunterricht\/home\/#!\/Home Blume, B. Instagram. Abgerufen am 12.01.2021 von https:\/\/www.instagram.com\/tv\/CJ5nUpzKeBg\/?igshid=1a347jkq5a0jf. BW LMZ-Brosch\u00fcre &#8222;Impulse zum Unterrichten mit Videokonferenzsystemen&#8220; &hellip; <\/p>","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[538],"tags":[],"kooperation":[],"licence":[],"mitwirkende":[],"class_list":["post-36834","online-kurs","type-online-kurs","status-publish","hentry","category-eteaching-expert"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht NRW Handreichung zur lernf\u00f6rderlichen Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht Abgerufen am 17. August 2020 von https:\/\/brosch\u00fcren.nrw\/distanzunterricht\/home\/#!\/Home Blume, B. Instagram. Abgerufen am 12.01.2021 von https:\/\/www.instagram.com\/tv\/CJ5nUpzKeBg\/?igshid=1a347jkq5a0jf. BW LMZ-Brosch\u00fcre &#8222;Impulse zum Unterrichten mit Videokonferenzsystemen&#8220; &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T10:37:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\\\/\",\"name\":\"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2020-11-17T12:39:52+00:00\",\"dateModified\":\"2023-12-11T10:37:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/","og_locale":"en_US","og_type":"article","og_title":"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen","og_description":"&nbsp; Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht NRW Handreichung zur lernf\u00f6rderlichen Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht Abgerufen am 17. August 2020 von https:\/\/brosch\u00fcren.nrw\/distanzunterricht\/home\/#!\/Home Blume, B. Instagram. Abgerufen am 12.01.2021 von https:\/\/www.instagram.com\/tv\/CJ5nUpzKeBg\/?igshid=1a347jkq5a0jf. BW LMZ-Brosch\u00fcre &#8222;Impulse zum Unterrichten mit Videokonferenzsystemen&#8220; &hellip;","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2023-12-11T10:37:24+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/","name":"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2020-11-17T12:39:52+00:00","dateModified":"2023-12-11T10:37:24+00:00","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/weiterfuehrende-links-zur-verknuepfung-von-praesenz-und-distanzunterricht\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"Weiterf\u00fchrende Links zur Verkn\u00fcpfung von Pr\u00e4senz- und Distanzunterricht"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/36834","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=36834"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=36834"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=36834"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=36834"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=36834"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=36834"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}