{"id":61780,"date":"2022-08-31T11:02:02","date_gmt":"2022-08-31T09:02:02","guid":{"rendered":"https:\/\/zfl-lernen.de\/?page_id=61780"},"modified":"2024-04-26T10:45:29","modified_gmt":"2024-04-26T08:45:29","slug":"fachlicher-hintergrund","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/","title":{"rendered":"Fachlicher Hintergrund"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Fachlicher Hintergrund<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"200\" height=\"200\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_lernstart.png\" class=\"vc_single_image-img attachment-medium\" alt=\"Lernstart\" title=\"ico_lernstart\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_lernstart.png 200w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_lernstart-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_lernstart-12x12.png 12w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Der fachliche Hintergrund informiert Sie dar\u00fcber&#8230;<\/p>\n<ul>\n<li>was es bedeutet, in einer <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/datengesellschaft\/\">Datengesellschaft<\/a><\/strong> zu leben.<\/li>\n<li>was f\u00fcr <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs-big-data-literacy\/wechselwirkungen\/\">Wechselwirkungen zwischen Mensch, Digitaltechnologie und sozialer Welt<\/a> <\/strong>bestehen.<\/li>\n<li>was <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/bigdata\/\">&#8222;Big Data&#8220;<\/a><\/strong>\u00a0meint.<\/li>\n<li>weshalb <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/datenrationalitaet\/\">Datenrationalit\u00e4t, Glaube und Diskriminierung<\/a> <\/strong>ein Problem sind.<\/li>\n<li>was <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/ueberwachungskapitalismus\/\">&#8222;\u00dcberwachungskapitalismus&#8220;<\/a><\/strong> ist.<\/li>\n<li>was <strong><a class=\"tc-menu-inner\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/big-data-literacy\/\">&#8222;Big Data Literacy&#8220;<\/a><\/strong>\u00a0ist, welche Bedeutung es hat und gibt einen \u00dcberblick \u00fcber den konzeptuellen Rahmen von neuen Kompetenzen in Bezug auf Big Data Literacy.<\/li>\n<\/ul>\n<p>In Anschluss k\u00f6nnen Sie in den so genannten <strong><a href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/stories\/\">&#8222;Stories&#8220;<\/a><\/strong>\u00a0(siehe rosa Bereich in der Navigation) anhand der beispielhaften Umsetzung von Szenarien und Fallbeispielen sehen, wie Sie bestimmte Themen selbstst\u00e4ndig in der Datenbank <strong><a href=\"https:\/\/www.bigdataliteracy.net\/\" target=\"_blank\" rel=\"noopener\">&#8222;bigdataliteracy.net&#8220;<\/a><\/strong>\u00a0recherchieren k\u00f6nnen.<\/p>\n<p>Au\u00dferdem finden Sie zum Abschluss die vollst\u00e4ndige <strong><a href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/literatur-hinweise\/\">Literaturliste und weiterf\u00fchrende Hinweise<\/a><\/strong> (grauer Bereich im Men\u00fc) zum Thema Big Data Literacy.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-block vc_btn3-color-black\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/ueber-diesen-kurs\/\" title=\"\u00dcber den Kurs\">zur\u00fcck<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_btn3-container vc_btn3-center vc_do_btn\" ><a class=\"vc_general vc_btn3 vc_btn3-size-md vc_btn3-shape-rounded vc_btn3-style-flat vc_btn3-block vc_btn3-color-black\" href=\"https:\/\/zfl-lernen.de\/en\/big-data-literacy\/datengesellschaft\/\" title=\"Leben in der Datengesellschaft\">weiter<\/a><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-3\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Fachlicher Hintergrund Der fachliche Hintergrund informiert Sie dar\u00fcber... was es bedeutet, in einer Datengesellschaft zu leben. was f\u00fcr Wechselwirkungen zwischen Mensch, Digitaltechnologie und sozialer Welt bestehen. was \"Big Data\"\u00a0meint. weshalb Datenrationalit\u00e4t, Glaube und Diskriminierung ein Problem sind. was \"\u00dcberwachungskapitalismus\" ist. &hellip;","protected":false},"author":31,"featured_media":0,"parent":45507,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[661],"tags":[821,1135,1136],"kooperation":[],"licence":[596],"mitwirkende":[],"class_list":["post-61780","online-kurs","type-online-kurs","status-publish","hentry","category-big-data-literacy","tag-big-data-literacy","tag-einfuehrung","tag-fachlicher-hintergrund","licence-cc-by-sa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fachlicher Hintergrund - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fachlicher Hintergrund - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2024-04-26T08:45:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/fachlicher-hintergrund\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/fachlicher-hintergrund\\\/\",\"name\":\"Fachlicher Hintergrund - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2022-08-31T09:02:02+00:00\",\"dateModified\":\"2024-04-26T08:45:29+00:00\",\"description\":\"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/fachlicher-hintergrund\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/fachlicher-hintergrund\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/fachlicher-hintergrund\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Big Data Literacy\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/big-data-literacy\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Fachlicher Hintergrund\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fachlicher Hintergrund - ZfL Lernen","description":"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/","og_locale":"en_US","og_type":"article","og_title":"Fachlicher Hintergrund - ZfL Lernen","og_description":"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2024-04-26T08:45:29+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/","name":"Fachlicher Hintergrund - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2022-08-31T09:02:02+00:00","dateModified":"2024-04-26T08:45:29+00:00","description":"Was ist eigentlich Big-Data-Literacy? Wobei kann es uns helfen? Was gibt es zu beachten? Eine Einf\u00fchrung zum fachlichen Hintergrund","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/fachlicher-hintergrund\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"Big Data Literacy","item":"https:\/\/zfl-lernen.de\/online-kurs\/big-data-literacy\/"},{"@type":"ListItem","position":4,"name":"Fachlicher Hintergrund"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/61780","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/31"}],"up":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/45507"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=61780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=61780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=61780"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=61780"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=61780"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=61780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}