{"id":63640,"date":"2022-11-10T10:05:22","date_gmt":"2022-11-10T09:05:22","guid":{"rendered":"https:\/\/zfl-lernen.de\/?page_id=63640"},"modified":"2023-12-11T11:37:31","modified_gmt":"2023-12-11T10:37:31","slug":"methodenkiste-projektmanagement","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/","title":{"rendered":"Methodenkiste &#8211; Projektmanagement"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h1>Methodenkiste &#8211; Projektmanagement<\/h1>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<div class=\"wpb_text_column wpb_content_element\">\n<div class=\"wpb_wrapper\">\n<p>Der Themenbereich &#8222;Projektmanagement&#8220; beinhaltet Methoden, die bei der Planung von einzelnen Aufgabenpaketen sowie langfristig angelegten Projekten unterst\u00fctzen k\u00f6nnen. Gr\u00f6\u00dfere Aufgaben k\u00f6nnen in einzelne Teilaufgaben innerhalb des Teams aufgeteilt werden oder Sie nutzen beispielsweise das KANBAN-Board als Einzelperson zur Aufgabenstrukturierung innerhalb einer Woche oder eines Arbeitstages.<br \/>\nHier finden Sie hilfreiche Tipps sowie zus\u00e4tzliche Erl\u00e4uterungen zur Organisation Ihrer Projekte.<\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n<p><em>Klicken Sie auf ein Plus-Symbol, um die jeweilige Methode kennen zu lernen. Es \u00f6ffnet sich ein Bild mit einer Beschreibung der Methode. Die im Bild enthaltenen Links finden Sie unter diesem zum Anklicken. Darunter haben Sie auch die M\u00f6glichkeit, die Methode als PDF herunterzuladen.<\/em><\/p>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"h5p-iframe-wrapper\"><iframe id=\"h5p-iframe-930\" class=\"h5p-iframe\" data-content-id=\"930\" style=\"height:1px\" src=\"about:blank\" frameborder=\"0\" scrolling=\"no\" title=\"Methodenkiste_Projektmanagement\"><\/iframe><\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Methodenkiste - Projektmanagement Der Themenbereich \"Projektmanagement\" beinhaltet Methoden, die bei der Planung von einzelnen Aufgabenpaketen sowie langfristig angelegten Projekten unterst\u00fctzen k\u00f6nnen. Gr\u00f6\u00dfere Aufgaben k\u00f6nnen in einzelne Teilaufgaben innerhalb des Teams aufgeteilt werden oder Sie nutzen beispielsweise das KANBAN-Board als Einzelperson &hellip;","protected":false},"author":32,"featured_media":0,"parent":63631,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"kooperation":[],"licence":[],"mitwirkende":[],"class_list":["post-63640","online-kurs","type-online-kurs","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Methodenkiste - Projektmanagement - ZfL Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Methodenkiste - Projektmanagement - ZfL Lernen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2023-12-11T10:37:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/methodenkiste-projektmanagement\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/methodenkiste-projektmanagement\\\/\",\"name\":\"Methodenkiste - Projektmanagement - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2022-11-10T09:05:22+00:00\",\"dateModified\":\"2023-12-11T10:37:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/methodenkiste-projektmanagement\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/methodenkiste-projektmanagement\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/methodenkiste-projektmanagement\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ZfL-Methodenkiste\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/methodenkiste\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Methodenkiste &#8211; Projektmanagement\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Methodenkiste - Projektmanagement - ZfL Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/","og_locale":"en_US","og_type":"article","og_title":"Methodenkiste - Projektmanagement - ZfL Lernen","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2023-12-11T10:37:31+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/","name":"Methodenkiste - Projektmanagement - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2022-11-10T09:05:22+00:00","dateModified":"2023-12-11T10:37:31+00:00","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/methodenkiste-projektmanagement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"ZfL-Methodenkiste","item":"https:\/\/zfl-lernen.de\/online-kurs\/methodenkiste\/"},{"@type":"ListItem","position":4,"name":"Methodenkiste &#8211; Projektmanagement"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/63640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/32"}],"up":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/63631"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=63640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=63640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=63640"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=63640"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=63640"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=63640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}