{"id":78534,"date":"2024-06-17T16:01:49","date_gmt":"2024-06-17T14:01:49","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=online-kurs&#038;p=78534"},"modified":"2025-03-31T14:02:14","modified_gmt":"2025-03-31T12:02:14","slug":"forschendes-lernen-eop","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/","title":{"rendered":"Forschendes Lernen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Forschendes Lernen<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element  flex_container__image\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper vc_box_circle  vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Grafik_Forschendes_Lernen-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Icon Forschendes Lernen\" title=\"Grafik_Forschendes_Lernen\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Grafik_Forschendes_Lernen-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Grafik_Forschendes_Lernen-12x12.png 12w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/Grafik_Forschendes_Lernen.png 250w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Hier finden Sie alles Wissenswerte zum Forschenden Lernen: Hintergrundinformationen zum Forschenden Lernen im EOP und\u00a0 inhaltlichen Input zu Forschungsmethoden.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1708977511007 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>Inhalts\u00fcbersicht:<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li><strong><a href=\"#fllehramtsstudium\">Forschendes Lernen im Lehramtsstudium<\/a><\/strong><\/li>\n<li><strong><a href=\"#forschenEOP\">Forschendes Lernen im Eignungs- und Orientierungspraktikum<\/a><\/strong><\/li>\n<li><a href=\"#blendedlearning\"><b>Das Konzept des Blended Learning im Forschenden Lernen\u00a0<\/b><\/a><\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><\/div><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"fllehramtsstudium\">Forschendes Lernen im Lehramtsstudium<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Das Forschende Lernen ist ein <strong>wichtiges Element aller Praxisphasen<\/strong> im Lehramtsstudium. Es ist ein hochschuldidaktisches Konzept, welches das theoriegeleitete, selbstreflexive und metakognitive Lernen unterst\u00fctzt und eine Verbindung von Theorie, Forschung und Praxis erm\u00f6glicht. Im Rahmen des Forschenden Lernens gestalten und reflektieren Sie den Prozess eines (kleineren) Forschungsvorhabens und k\u00f6nnen so eine forschend-reflexive Haltung entwickeln.<\/p>\n<p style=\"text-align: justify\">Im <strong>Eignungs- und Orientierungspraktikum<\/strong> untersuchen Sie eine Fragestellung mit der Methode des Forschenden Lernens. Im <strong>Berufsfeldpraktikum<\/strong> werden Sie das\u00a0Forschende Lernen fortsetzen, indem Sie eine Untersuchungsfrage mithilfe einer der beiden Forschungsmethoden Leitfadeninterview oder Fragebogen bearbeiten. Im <strong>Praxissemester<\/strong> setzen Sie dann ein umfangreicheres <strong><a href=\"https:\/\/zfl.uni-koeln.de\/praxisphasen\/praxissemester\/studienprojekt-eportfolio\" target=\"_blank\" rel=\"noopener\">Studienprojekt<\/a> <\/strong>im Rahmen des Forschenden Lernens um.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" id=\"forschenEOP\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"flbfp\">Forschendes Lernen im Eignungs- und Orientierungspraktikum<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"flex-shrink-0 flex flex-col relative items-end\">\n<div>\n<div class=\"pt-0\">\n<div class=\"gizmo-bot-avatar flex h-8 w-8 items-center justify-center overflow-hidden rounded-full\">\n<div class=\"relative p-1 rounded-sm flex items-center justify-center bg-token-main-surface-primary text-token-text-primary h-8 w-8\" style=\"text-align: justify\"><span style=\"color: #000000\">Im Rahmen des Eignungs- und Orientierungspraktikums erfolgt der Einstieg in das Forschende Lernen in Form von definierten Beobachtungsfragen. Sie entwickeln eine\u00a0<strong>Beobachtungsfrage<\/strong>\u00a0und werden dazu innerhalb ihres Lernteams auch durch Ihre*n Dozierende*n in einer\u00a0<strong>Beratungssitzung<\/strong> begleitet. W\u00e4hrend Ihres Blockpraktikums in der Schule f\u00fchren Sie anhand eines Beobachtungsbogens eine <strong>Beobachtung<\/strong> durch, die Sie anschlie\u00dfend in Ihren Portfolio dokumentieren und reflektieren.<\/span><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" id=\"blendedlearning\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Das Konzept des Blended Learning im Foschenden Lernen<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\"><span style=\"color: #000000\">Das Forschende Lernen im EOP folgt dem <strong>Konzept des Blended Learning.<\/strong>\u00a0Hierbei werden <strong>synchrone und asynchrone Lehr-Lern-Formate<\/strong> miteinander verzahnt mit dem Ziel, die St\u00e4rken beider Formate zu nutzen. Eine Variante des Blended Learning, die im EOP angewendet wird, ist der <strong><a style=\"color: #000000\" href=\"https:\/\/portal.uni-koeln.de\/sites\/uni\/images\/Studium\/digital_education\/2022-04-01-Fact-Sheet-Flipped-Classroom.pdf\" target=\"_blank\" rel=\"noopener\">Flipped Classroom<\/a>.<\/strong> Hierbei wird die traditionelle Lehre \u201cgeflippt\u201d: Die <strong>Vermittlung von Informationen<\/strong> erfolgt zun\u00e4chst asynchron \u00fcber digitales Lernmaterial, das Sie selbstst\u00e4ndig in Ihrem eigenen Tempo zu Hause bearbeiten. So erarbeiten Sie sich zum Beispiel das Grundlagenwissen zu einer Forschungsmethode. Die synchronen Lehrveranstaltungen in Pr\u00e4senz oder online dienen der <strong>Anwendung der Inhalte oder dem Austausch<\/strong>.\u00a0<\/span><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Forschendes Lernen Hier finden Sie alles Wissenswerte zum Forschenden Lernen: Hintergrundinformationen zum Forschenden Lernen im EOP und\u00a0 inhaltlichen Input zu Forschungsmethoden. Inhalts\u00fcbersicht: Forschendes Lernen im Lehramtsstudium Forschendes Lernen im Eignungs- und Orientierungspraktikum Das Konzept des Blended Learning im Forschenden Lernen\u00a0 &hellip;","protected":false},"author":4,"featured_media":0,"parent":78276,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[717],"tags":[837,1031,1032,1022],"kooperation":[],"licence":[596],"mitwirkende":[],"class_list":["post-78534","online-kurs","type-online-kurs","status-publish","hentry","category-bfp-begleitkurs-digital","tag-bfp","tag-interview","tag-lernmodule","tag-uni-koeln","licence-cc-by-sa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Forschendes Lernen - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Forschendes Lernen - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T12:02:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/forschendes-lernen-eop\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/forschendes-lernen-eop\\\/\",\"name\":\"Forschendes Lernen - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2024-06-17T14:01:49+00:00\",\"dateModified\":\"2025-03-31T12:02:14+00:00\",\"description\":\"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/forschendes-lernen-eop\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/forschendes-lernen-eop\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/forschendes-lernen-eop\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Praxisphasentransparenz\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"EOP digitaler Begleitkurs\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/eop-digitaler-begleitkurs\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Forschendes Lernen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Forschendes Lernen - ZfL Lernen","description":"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/","og_locale":"en_US","og_type":"article","og_title":"Forschendes Lernen - ZfL Lernen","og_description":"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2025-03-31T12:02:14+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/","name":"Forschendes Lernen - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2024-06-17T14:01:49+00:00","dateModified":"2025-03-31T12:02:14+00:00","description":"Forschendes Lernen w\u00e4hrend des BFP. Informationen zu Planung, Umsetzung, und Auswertung. Bereitgestellt von der Universit\u00e4t zu K\u00f6ln.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/forschendes-lernen-eop\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"Praxisphasentransparenz","item":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/"},{"@type":"ListItem","position":4,"name":"EOP digitaler Begleitkurs","item":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/eop-digitaler-begleitkurs\/"},{"@type":"ListItem","position":5,"name":"Forschendes Lernen"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/78534","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"up":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/78276"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=78534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=78534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=78534"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=78534"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=78534"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=78534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}