{"id":78657,"date":"2024-06-26T08:17:53","date_gmt":"2024-06-26T06:17:53","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=online-kurs&#038;p=78657"},"modified":"2025-10-22T15:49:05","modified_gmt":"2025-10-22T13:49:05","slug":"informationen","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/","title":{"rendered":"Informationen"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h2>Informationen<\/h2>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Hier finden Sie <strong>wichtige Informationen und rechtliche Rahmenbedingungen<\/strong> f\u00fcr Ihr Berufsfeldpraktikum und das Modul BFP. Bitte lesen Sie die Hinweise aufmerksam durch \u2013 am besten zu Beginn des Semesters, in dem Sie Ihr Begleitseminar belegen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1611733284514 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 28px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>Inhalts\u00fcbersicht<\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ul>\n<li><strong><a href=\"#ablauf\">\u00dcbersicht \u00fcber den Verlauf des Moduls<\/a><\/strong><\/li>\n<li><strong><a href=\"#informationen\">Informationen zum Praktikum und zum Modulabschluss<\/a><\/strong><\/li>\n<li><strong><a href=\"#checkliste\">Dokumente und Informationen<\/a><\/strong><\/li>\n<li><strong><a href=\"#praktikumsplatz\">Praktikumsstellen<\/a><\/strong><\/li>\n<li><strong><a href=\"#tipps\">Bewerbungstipps<\/a><\/strong><\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" id=\"ablauf\">\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Verlauf des Moduls<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Belegung des Seminars zur Begleitung des BFP<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Sie melden sich f\u00fcr ein Seminar \u201eBegleitung des Berufsfeldpraktikums\u201c unter KLIPS 2.0 an. Wir bieten verschiedene Seminare an, auch mit spezifischen Schwerpunkten (Informationen finden Sie in den Inhaltsangaben bzw. Kommentaren des jeweiligen Seminars in KLIPS).<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Besuch des Seminars zur Begleitung des BFP<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Sie besuchen die Vorbereitungsphase des Seminars und bearbeiten die Portfolio-Aufgaben f\u00fcr die Zeit vor dem Praktikum. Weitere Aufgaben, die Sie w\u00e4hrend des Praktikums und nach dem Praktikum bearbeiten m\u00fcssen, werden Ihnen im Seminar bekannt gegeben.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Praktikum<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Sie suchen eigenverantwortlich einen geeigneten Praktikumsplatz, der in Verbindung mit einem Wahlthema bzw. einem Schwerpunkt steht. Bitte stellen Sie sicher, dass Sie bis zur 6. Seminarsitzung einen Praktikumsplatz in Aussicht haben.\u00a0 Sie bearbeiten parallel zum Berufsfeldpraktikum die Portfolio-Aufgaben f\u00fcr die Praktikumszeit. (Mehr Informationen finden Sie in den \u201e<a href=\"#tipps\">Bewerbungstipps<\/a>\u201c.)<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>ePortfolio<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Laut<strong>\u00a0<a href=\"https:\/\/recht.nrw.de\/lmi\/owa\/br_bes_text?sg=1&amp;menu=1&amp;bes_id=12764&amp;aufgehoben=N&amp;anw_nr=2\" target=\"_blank\" rel=\"noopener\">LABG (2009)<\/a>\u00a0<\/strong>\u00a712 werden alle Praxiselemente \u201ein einem Portfolio dokumentiert\u201c. An der Universit\u00e4t zu K\u00f6ln wird dieses Portfolio als \u201eePortfolio\u201c gef\u00fchrt. Das obligatorische ePortfolio beinhaltet die Portfolio-Aufgaben, die Sie im ILIAS-Kurs Ihres Seminars finden. Sie bearbeiten die Portfolio-Aufgaben und schalten sie f\u00fcr Ihre*n Dozierende*n frei. Dies ist die Grundlage f\u00fcr die gemeinsame Abschlusssitzung.<\/p>\n<p style=\"text-align: justify\">Sie haben neben den vorgegebenen Reflexionsanregungen zus\u00e4tzlich die M\u00f6glichkeit, das Portfolio individuell zu gestalten und Themen, Materialien o. \u00c4. zu sammeln, die Sie in Ihren Praxisphasen besch\u00e4ftigen.<\/p>\n<p style=\"text-align: justify\">Aktuell entwickeln wir das ePortfolio in der Lehrer*innenbildung weiter. Da wir Ihnen eine optimale Ausbildung erm\u00f6glichen m\u00f6chten, beziehen wir Sie mit ein und freuen uns, dass Sie Teil eines Pilotdurchgangs sind, um das neue ePortfolio-Konzept zu testen. Eine erste Einf\u00fchrung haben Sie in der ersten Seminarsitzung erhalten. Weitere Informationen zum neuen ePortfolio finden Sie auf der <a href=\"https:\/\/zfl-lernen.de\/en\/faq-portfolio\/\" target=\"_blank\" rel=\"noopener\"><strong>FAQ-Seite.<\/strong><\/a><\/p>\n<p style=\"text-align: justify\">Wir freuen uns auf Ihr Feedback, Ihre Fragen und Anregungen!<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Forschendes Lernen<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Sie entwickeln eine eigene Untersuchungsfrage, die Sie im Laufe Ihres Praktikums mit einer geeigneten Forschungsmethode vorbereiten, durchf\u00fchren, auswerten und reflektieren. Dazu besch\u00e4ftigen Sie sich in der Woche zum Forschenden Lernen mit folgenden Themen:<\/p>\n<ul>\n<li style=\"text-align: justify\">Selbstlerneinheit zur Einf\u00fchrung in Forschungsmethoden<\/li>\n<li style=\"text-align: justify\">Lernmodulen zur Vertiefung einer Forschungsmethode (leitfadengest\u00fctztes Interview oder Fragebogen)<\/li>\n<li style=\"text-align: justify\">Workshop zur Entwicklung eines Interviewleitfadens ODER eines Fragebogens.<\/li>\n<\/ul>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Modulabschluss<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Sie<\/p>\n<ul style=\"text-align: justify\">\n<li>nehmen aktiv am Seminar teil und bearbeiten Seminaraufgaben,<\/li>\n<li>verfassen ein ePortfolio als begleitendes Reflexionselement mit einem Poster zum Forschenden Lernen,<\/li>\n<li>absolvieren das Praktikum und<\/li>\n<li>besuchen die obligatorische Abschlusssitzung mit Posterpr\u00e4sentation.<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Bitte melden Sie sich ab 1. M\u00e4rz eigenst\u00e4ndig zur Modulabschlusspr\u00fcfung in Klips 2.0 an. Bitte f\u00fcgen Sie die Bescheinigung \u00fcber das Berufsfeldpraktikum im Anschluss an das Praktikum, sp\u00e4testens bis zum 31. M\u00e4rz (im Anschluss an das WiSe) bzw. 30. September (SoSe) in Ihr Portfolio ein und laden Sie die Bescheinigung au\u00dferdem <a href=\"https:\/\/www.ilias.uni-koeln.de\/ilias\/ilias.php?ref_id=3513834&amp;target=3513834&amp;cmd=showOverview&amp;cmdClass=ilobjexercisegui&amp;cmdNode=c8:p2&amp;baseClass=ilexercisehandlergui\" target=\"_blank\" rel=\"noopener\"><strong>hier<\/strong><\/a> hoch (Hinweis: loggen Sie sich bitte erst in ILIAS ein, bevor Sie dem Link folgen, um erfolgreich auf den Abgabe-Ordner zugreifen zu k\u00f6nnen). Bescheinigungen, die nach dieser Frist eingereicht werden, k\u00f6nnen erst im folgenden Semester bearbeitet und verbucht werden. Bitte beachten Sie, dass nur vollst\u00e4ndige und lesbare Bescheinigungen bearbeitet werden k\u00f6nnen.<\/p>\n<p style=\"text-align: justify\">Weitere Informationen zur Modulabschlusspr\u00fcfung, insbesondere zu den Anmeldefristen, finden Sie auf unserer <strong><a href=\"https:\/\/zfl.uni-koeln.de\/praxisphasen\/berufsfeldpraktikum\/verlauf-abschluss#c158051\" target=\"_blank\" rel=\"noopener\">Homepage<\/a><\/strong>.<\/p>\n<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"informationen\">Informationen zum Praktikum und zum Modulabschluss<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Das Berufsfeldpraktikum (BFP) ist die zweite Praxisphase innerhalb des Bachelor-Lehramtsstudiums. Das Modul umfasst das Begleitseminar in Kombination mit der in der Regel au\u00dferschulischen Praxisphase, die \u201ekonkretere berufliche Perspektiven au\u00dferhalb des Schuldienstes er\u00f6ffnet oder Einblicke in die f\u00fcr den Lehrerberuf relevanten au\u00dferschulischen T\u00e4tigkeitsfelder gew\u00e4hrt\u201c. <sub><strong><a href=\"https:\/\/recht.nrw.de\/lmi\/owa\/br_bes_text?sg=1&amp;menu=1&amp;bes_id=12764&amp;aufgehoben=N&amp;anw_nr=2\" target=\"_blank\" rel=\"noopener\">LABG (2009)<\/a> <\/strong>\u00a7 12 Abs. 2\u00a0<\/sub><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Das Praktikum<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Folgende Rahmenbedingungen sind f\u00fcr Ihr Praktikum relevant:<\/p>\n<ul>\n<li style=\"text-align: justify\">mindestens <b>20 Tage mit mindestens 80<\/b>\u00a0<b>Zeitstunden<\/b> <b>aktiver Lernzeit<\/b><\/li>\n<li style=\"text-align: justify\"><strong>semesterbegleitend oder im Block<\/strong><\/li>\n<li style=\"text-align: justify\">Begleitseminar und Praktikum m\u00fcssen im selben Semester absolviert werden<\/li>\n<li style=\"text-align: justify\">im au\u00dferschulischen Bereich <strong><a href=\"https:\/\/recht.nrw.de\/lmi\/owa\/br_bes_text?sg=1&amp;menu=1&amp;bes_id=12764&amp;aufgehoben=N&amp;anw_nr=2\" target=\"_blank\" rel=\"noopener\">(LABG 2009)<\/a><\/strong><\/li>\n<li style=\"text-align: justify\">von der Universit\u00e4t begleitet (Seminar)<\/li>\n<li style=\"text-align: justify\">in Deutschland oder<strong> <a href=\"https:\/\/zfl.uni-koeln.de\/bachelor\/auslandsaufenthalt\" target=\"_blank\" rel=\"noopener\">im Ausland<\/a><\/strong> m\u00f6glich<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Der Modulabschluss<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Das Portfolio stellt (gemeinsam mit dem erfolgreichen Abschluss des Begleitseminars und dem praktischen Teil des Eignungs- und Orientierungspraktikums) die Modulabschlusspr\u00fcfung (MAP) dar. Zur Verbuchung der Leistungspunkte m\u00fcssen Sie folgende Leistungen erbringen:<\/p>\n<ul style=\"text-align: justify\">\n<li>aktive Teilnahme am Seminar und Bearbeitung der Seminaraufgaben<\/li>\n<li>Teilnahme an der Abschlusssitzung mit Posterpr\u00e4sentation<\/li>\n<li>Portfolioarbeit inklusive Poster<\/li>\n<li>Absolvieren des Praktikums<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Weitere Informationen zur Modulabschlusspr\u00fcfung finden Sie auf unserer <a href=\"https:\/\/zfl.uni-koeln.de\/praxisphasen\/berufsfeldpraktikum\/verlauf-abschluss#c158051\" target=\"_blank\" rel=\"noopener\"><strong>Homepage<\/strong>.<\/a><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"checkliste\">Dokumente und Informationen<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Hier finden Sie wichtige Informationen, die Sie vor dem Beginn Ihres Praktikums lesen sollten sowie Dokumente, die Sie f\u00fcr Ihr BFP ben\u00f6tigen.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Icon Hinweis\" title=\"ico_hinweis\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis-12x12.png 12w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png 200w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Die folgenden Informationen sind besonders wichtig. <strong>Bitte setzen Sie sich fr\u00fchzeitig damit auseinander, da Sie sonst Ihr Praktikum nicht antreten k\u00f6nnen. <\/strong>Einige Dokumente m\u00fcssen Sie ausgedruckt und unterschrieben zu Beginn Ihres Praktikums abgeben. Falls Sie Ihr Praktikum im p\u00e4dagogischen oder sozialen Bereich absolvieren, k\u00f6nnen Sie die Informationen zur Verschwiegenheitspflicht und die Belehrung zum Infektionsschutz verwenden.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Versicherungsschutz<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\"><b>Unfallversicherung<\/b><\/p>\n<p style=\"text-align: justify\">W\u00e4hrend des Praktikums sind\u00a0Sie unentgeltlich gesetzlich unfallversichert. Somit ist auch Ihr allt\u00e4glicher Weg von Zuhause zum Praktikumsort sowie der Weg vom Praktikumsort nach Hause in unfallrechtlicher Hinsicht abgesichert. Im Schadensfall werden Sie wie vertraglich gebundene Arbeitnehmer*innen behandelt und die gesetzliche Unfallversicherung greift.<\/p>\n<p style=\"text-align: justify\"><b>Haftpflichtversicherung<\/b><\/p>\n<p style=\"text-align: justify\">Zu Ihrer eigenen Absicherung ist es ratsam, vor dem Praktikum eine private Haftpflichtversicherung abzuschlie\u00dfen.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Checkliste f\u00fcr den Start in das BFP<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Diese Checkliste enth\u00e4lt alle wichtigen Schritte f\u00fcr den Einstieg in das BFP.<\/p>\n<p style=\"text-align: justify\">Sie k\u00f6nnen <a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Checkliste_Vorbereitung-3.pdf\" target=\"_blank\" rel=\"noopener\"><strong>die Checkliste hier<\/strong><\/a> herunterladen.<\/p>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Checkliste_Vorbereitung-3.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">BFP-Begleitkurs-digital_Informationen_I_Checkliste_Vorbereitung-3<\/a><\/div>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Infos zur Verschwiegenheitspflicht<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Bitte <strong>drucken<\/strong> Sie die Informationen zur Verschwiegenheitspflicht bei Bedarf aus. Bitte best\u00e4tigen Sie das Schreiben durch Ihre <strong>Unterschrift<\/strong> und <strong>reichen es bei Ihrer Praktikumsstelle ein<\/strong>.<\/p>\n<p style=\"text-align: justify\">Sie k\u00f6nnen <a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Belehrung_Verschwiegenheit.pdf\"><strong>das Schreiben hier<\/strong><\/a> herunterladen.<\/p>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Belehrung_Verschwiegenheit.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">BFP-Begleitkurs-digital_Informationen_I_Belehrung_Verschwiegenheit<\/a><\/div>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Infos zur Belehrung Infektionsschutz<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Bitte <strong>drucken<\/strong> Sie die Belehrung zum Infektionsschutz bei Bedarf (i. d. R. Praktikum im sozialen oder p\u00e4dagogischen Bereich) aus. Bitte best\u00e4tigen Sie das Schreiben durch Ihre <strong>Unterschrift<\/strong> und <strong>reichen es bei Ihrer Praktikumsstelle ein<\/strong>.<\/p>\n<p style=\"text-align: justify\">Sie k\u00f6nnen <strong><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Belehrung_Infektionsschutzgesetz.pdf\">die Belehrung hier<\/a><\/strong> herunterladen.<\/p>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Belehrung_Infektionsschutzgesetz.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">BFP-Begleitkurs-digital_Informationen_I_Belehrung_Infektionsschutzgesetz<\/a><\/div>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Best\u00e4tigung des Praktikumsplatzes durch die Praktikumsstelle<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p>Es ist sinnvoll, wenn Sie sich Ihren Praktikumsplatz von der Praktikumsstelle schriftlich best\u00e4tigen lassen. Diese Best\u00e4tigung ist nur <strong>f\u00fcr Ihre Unterlagen und Planungssicherheit<\/strong> bestimmt. Sie m\u00fcssen es <strong>nicht beim ZfL einreichen.<\/strong><\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Handreichung f\u00fcr Praktikumsgeber*innen<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Hier finden Sie eine Handreichung mit den wichtigsten Informationen zum BFP f\u00fcr Ihre Praktikumsstelle.<\/p>\n<p style=\"text-align: justify\">Bitte lesen Sie die Handreichung durch und bringen Sie sie Ihrer Praktikumsstelle zu Beginn des Praktikums mit.<\/p>\n<p style=\"text-align: justify\">Sie k\u00f6nnen die Handreichung auf <strong><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Handreichung_Berufsfeldpraktikum.pdf\">Deutsch<\/a><\/strong> und auf <a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Handreichung-Berufsfeldpraktikum-englisch.pdf\"><strong>Englisch<\/strong><\/a> herunterladen.<\/p>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/BFP-Begleitkurs-digital_Informationen_I_Handreichung_Berufsfeldpraktikum.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">BFP-Begleitkurs-digital_Informationen_I_Handreichung_Berufsfeldpraktikum<\/a><\/div>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/Handreichung-Berufsfeldpraktikum-englisch.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">Handreichung-Berufsfeldpraktikum-englisch<\/a><\/div>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Praktikumsbescheinigung zum BFP<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Am Ende des Praktikums bescheinigt Ihnen die Praktikumsstelle das Praktikum. Bitte denken Sie daran, diese <a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_Praktikum_Bescheinigung_BFP.pdf\" target=\"_blank\" rel=\"noopener\"><strong>Praktikumsbescheinigung<\/strong><\/a> vorzulegen und unterschrieben und gestempelt zu Ihren Unterlagen zu nehmen. Sie ben\u00f6tigen die Bescheinigung f\u00fcr Ihren Modulabschluss. Bitte f\u00fcgen Sie die Bescheinigung \u00fcber das Berufsfeldpraktikum im Anschluss an das Praktikum in Ihr Portfolio ein und laden Sie die Bescheinigung au\u00dferdem <strong><a href=\"https:\/\/uni.koeln\/8AYX3\" target=\"_blank\" rel=\"noopener\">hier<\/a><\/strong>\u00a0hoch.<\/p>\n<p style=\"text-align: justify\">Die Praktikumsbescheinigung in englischer Sprache k\u00f6nnen Sie\u00a0<a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_Vocation-Field-Internship.pdf\" target=\"_blank\" rel=\"noopener\"><strong>hier<\/strong><\/a>\u00a0herunterladen.<\/p>\n<p style=\"text-align: justify\">\n<div class=\"wp-block-pdfemb-pdf-embedder-viewer\"><a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_Praktikum_Bescheinigung_BFP.pdf\" class=\"pdfemb-viewer\" style=\"\" data-width=\"max\" data-height=\"max\" data-toolbar=\"bottom\" data-toolbar-fixed=\"off\">ZfL_Praktikum_Bescheinigung_BFP<\/a><\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"praktikumsplatz\">Praktikumsstellen<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Zugelassen als Praktikumsstellen sind Institutionen oder Einrichtungen mit einem<\/p>\n<ul style=\"text-align: justify\">\n<li>p\u00e4dagogischen<\/li>\n<li>fachlichen Bezug (F\u00e4cher, die Sie studieren).<\/li>\n<\/ul>\n<p style=\"text-align: justify\">Sie k\u00f6nnen Ihr BFP in ganz Deutschland absolvieren. Liegt die Praktikumsstelle nicht in NRW, erkundigen Sie sich bitte nach der Unfallversicherung in dem jeweiligen Bundesland.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>M\u00f6gliche Praktikumsstellen<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\"><strong><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-31952 alignleft\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png\" alt=\"Icon Hinweis\" width=\"60\" height=\"60\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png 200w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis-12x12.png 12w\" sizes=\"auto, (max-width: 60px) 100vw, 60px\" \/><\/strong>Ihre Praktikumsstelle muss offiziell Praktikumspl\u00e4tze anbieten d\u00fcrfen. Privatpersonen geh\u00f6ren nicht dazu, da hier ggf. kein Praktikumsvertrag geschlossen werden kann und der Versicherungsschutz dann nicht gew\u00e4hrleistet sein kann.<\/p>\n<p style=\"text-align: justify\">M\u00f6glich sind dagegen Praktika in z. B.<\/p>\n<ul>\n<li style=\"text-align: justify\">p\u00e4dagogischen Einrichtungen<\/li>\n<li style=\"text-align: justify\">Vereinen (e.V.)<\/li>\n<li style=\"text-align: justify\">(\u00f6ffentlichen, freien oder kirchlichen) Tr\u00e4gern<\/li>\n<li style=\"text-align: justify\">Wohlfahrtsverb\u00e4nden<\/li>\n<li style=\"text-align: justify\">Unternehmen (bei fachlichem Bezug)<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3><strong>BFP im Ausland <\/strong><\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-8\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\">Es ist m\u00f6glich, das BFP im Ausland zu absolvieren. Hier haben Sie auch die M\u00f6glichkeit, das BFP schulisch zu absolvieren. Hierzu werden auch Seminare mit dem Schwerpunkt zur Vorbereitung auf den Auslandsaufenthalt angeboten, Sie k\u00f6nnen aber auch eines der regul\u00e4ren Seminare zur \u201eBegleitung des Berufsfeldpraktikums\u201c belegen. Zudem besteht ein umfangreiches Beratungsangebot. Weitere Informationen finden Sie auf unserer Webseite zum <strong><a href=\"https:\/\/zfl.uni-koeln.de\/praxisphasen\/berufsfeldpraktikum\/praktikumsplatz#c151144\" target=\"_blank\" rel=\"noopener\">Berufsfeldpraktikum im Ausland.<\/a><\/strong><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-4\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<a href=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-scaled-1024x671.jpg\" target=\"_self\" class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"1677\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-scaled.jpg\" class=\"vc_single_image-img attachment-full\" alt=\"Weltkarte mit einem Spielzeugflugzeug\" title=\"ZfL_LM_BFP-im-Ausland-digital\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-scaled.jpg 2560w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-scaled-300x197.jpg 300w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-scaled-1024x671.jpg 1024w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-768x503.jpg 768w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-1536x1006.jpg 1536w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ZfL_LM_BFP-im-Ausland-digital-1-2048x1342.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/a>\n\t\t<\/figure>\n\t<\/div>\n\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: center\"><sup class=\"sup\"><em>Foto: Andrea Piacquadio, Pexels<\/em><\/sup><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3 id=\"tipps\">Bewerbungstipps<\/h3>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p style=\"text-align: justify\"><strong>So finden Sie eine Praktikumsstelle<\/strong><\/p>\n<p style=\"text-align: justify\">Im Berufsfeldpraktikum haben Sie vielf\u00e4ltige M\u00f6glichkeiten. Sie k\u00f6nnen das Berufsfeldpraktikum in einer von Ihnen selbst gew\u00e4hlten Einrichtung oder Institution absolvieren.<\/p>\n<p style=\"text-align: justify\">Die Praktikumsplatzsuche liegt in Ihrer alleinigen Verantwortung.<\/p>\n<p style=\"text-align: justify\">Die Suche nach einer geeigneten Praktikumsstelle f\u00fcr das Berufsfeldpraktikum gestaltet sich in der Ausbildungsregion K\u00f6ln nicht immer einfach. Mit unseren Tipps m\u00f6chten wir Ihnen helfen, Ihre Bewerbung um einen Praktikumsplatz m\u00f6glichst professionell zu gestalten, um Ihre Chancen auf einen Praktikumsplatz zu verbessern.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Allgemeine Hinweise zur Bewerbung<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\"><strong>Die wichtigste Empfehlung: Bewerben Sie sich fr\u00fchzeitig!<\/strong><\/p>\n<p style=\"text-align: justify\">Sie sollten bei Ihrer Suche ein m\u00f6glichst <strong>breites Einzugsgebiet<\/strong> in den Blick nehmen und ggf. bereit sein, auch einen l\u00e4ngeren Anfahrtsweg in Kauf zu nehmen.<\/p>\n<p style=\"text-align: justify\"><strong>Kontaktaufnahme mit der Praktikumsstelle<\/strong><\/p>\n<p style=\"text-align: justify\">Vor der eigentlichen Bewerbung ist eine umfassende Internet-Recherche auf den Homepages der in Frage kommenden Institutionen\/Einrichtungen sinnvoll.<\/p>\n<p style=\"text-align: justify\">Es ist grunds\u00e4tzlich empfehlenswert, einen pers\u00f6nlichen Erstkontakt mit der Praktikumsstelle per Telefon aufzunehmen! Sie erfahren dann, ob die Institution\/Einrichtung \u00fcberhaupt Praktikumspl\u00e4tze vergeben kann und wer Ihr*e Ansprechpartner*in ist.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Kooperationspartner*innen des ZfL<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Das ZfL kooperiert mit zahlreichen Einrichtungen und Institutionen, die gerne Praktikumspl\u00e4tze f\u00fcr das Berufsfeldpraktikum zur Verf\u00fcgung stellen.\u00a0Um sich zu orientieren oder einen interessanten Praktikumsplatz zu finden, k\u00f6nnen Sie die <strong><a href=\"https:\/\/zfl.uni-koeln.de\/sites\/zfl\/Dokumente\/EOP-BFP\/bfp-kooperationspartner_innen.pdf\" target=\"_blank\" rel=\"noopener\">Kartei unserer Kooperationspartner*innen<\/a> <\/strong>nutzen.<\/p>\n<p style=\"text-align: justify\"><strong>Welche Bereiche interessieren Sie?<\/strong><\/p>\n<p style=\"text-align: justify\">Im BFP sind Praktikumsort und <a href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/wahlthemen\/\" target=\"_blank\" rel=\"noopener\"><strong>Wahlthema<\/strong><\/a> eng miteinander verbunden. In unserer <strong><a href=\"https:\/\/zfl.uni-koeln.de\/sites\/zfl\/Dokumente\/EOP-BFP\/bfp-kooperationspartner_innen.pdf\" target=\"_blank\" rel=\"noopener\">Kartei<\/a> <\/strong>finden Sie m\u00f6gliche Praktikumspl\u00e4tze anhand der BFP-Wahlthemen sortiert: Inklusive Bildung, Kulturelle Bildung, BNE oder Partizipation und Demokratiebildung. Das Angebot ist vielf\u00e4ltig!<\/p>\n<p style=\"text-align: justify\"><strong>Welche Zielgruppe interessiert Sie?<\/strong><\/p>\n<p style=\"text-align: justify\">Sie k\u00f6nnen auf einen Blick sehen, ob die Einrichtung\/Institution sich eher an (junge) Erwachsene, Jugendliche oder Kinder richtet und k\u00f6nnen entscheiden, mit welcher Zielgruppe Sie noch Erfahrung sammeln m\u00f6chten.<\/p>\n<p style=\"text-align: justify\"><strong>Suchen Sie einen barrierefreien Praktikumsplatz?<\/strong><\/p>\n<p style=\"text-align: justify\">Unsere Kooperationspartner*innen geben an, ob der Praktikumsplatz barrierefrei, zum Teil barrierefrei oder nicht barrierefrei ist.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Schriftliche Bewerbung<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">In der Regel fordern die Einrichtungen\/Institutionen von den Bewerber*innen eine kurze\u00a0<strong>schriftliche Bewerbung<\/strong>, die h\u00e4ufig aus einem\u00a0<strong>Anschreiben<\/strong>\u00a0und einem tabellarischen\u00a0<strong>Lebenslauf<\/strong>\u00a0besteht. Kopien von Zeugnissen und sonstigen Anlagen werden eher selten angefragt. Bitte richten Sie sich, wie bereits oben erw\u00e4hnt, hier jedoch genau nach den\u00a0<strong>Vorgaben der jeweiligen <\/strong><strong>Institution\/Einrichtung<\/strong>. Nutzen Sie die Chance, in der schriftlichen Bewerbung einen positiven ersten Eindruck zu hinterlassen und sich von Ihren Mitbewerber*innen abzuheben, indem sie die allgemein\u00a0<strong>g\u00fcltigen Standards<\/strong>\u00a0f\u00fcr das Erstellen von Bewerbungen ber\u00fccksichtigen. Dazu geh\u00f6ren insbesondere Schriftform, Aufbau, Design, Schreibstil, Fehlerfreiheit\u00a0usw.<\/p>\n<p style=\"text-align: justify\">Denken Sie auch daran, dass viele g\u00e4ngige Abk\u00fcrzungen aus dem Lehramt weiteren Institutionen nicht bekannt sind und Sie ggf. etwas mehr zu Ihrem Studium erkl\u00e4ren m\u00fcssen. Nehmen Sie pers\u00f6nlich (z. B. telefonisch) Kontakt auf, wenn Sie ca. zwei Wochen nach Ihrer schriftlichen Bewerbung keine R\u00fcckmeldung erhalten haben.<\/p>\n<\/div><\/div><div  class=\"vc_do_toggle vc_toggle vc_toggle_simple vc_toggle_color_default  vc_toggle_size_lg\"><div class=\"vc_toggle_title\"><h4>Pers\u00f6nliches Gespr\u00e4ch<\/h4><i class=\"vc_toggle_icon\"><\/i><\/div><div class=\"vc_toggle_content\"><p style=\"text-align: justify\">Wenn Sie zu einem pers\u00f6nlichen Gespr\u00e4ch eingeladen werden, sollten Sie sich darauf gut <strong>vorbereiten<\/strong> und entsprechend umfassend \u00fcber die Einrichtung\/Institution informieren. Bedenken Sie, dass es sich um eine <strong>Bewerbungssituation<\/strong> handelt und Sie sich dementsprechend auf das Gespr\u00e4ch vorbereiten (z. B. Ihren Lebenslauf zum Gespr\u00e4ch mitbringen).<\/p>\n<p style=\"text-align: justify\">Hier haben Sie auch die M\u00f6glichkeit, Ihre Vorstellungen von der Gestaltung des Praktikums einzubringen und den potentiellen <strong>Praktikumsablauf<\/strong> abzukl\u00e4ren. Bis zum Gespr\u00e4chstermin sollten alle geforderten <strong>Unterlagen<\/strong> vorliegen, damit im Gespr\u00e4ch darauf Bezug genommen werden kann.<\/p>\n<\/div><\/div><div class=\"vc_empty_space\"   style=\"height: 20px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dotted vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<details class=\"dropdown-content-details\">\n<summary class=\"dropdown-content-div\">\n<div class=\"dropdown-content-div\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-31955\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_literatur.png\" alt=\"Icon Literatur\" width=\"130\" height=\"130\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_literatur.png 200w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_literatur-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_literatur-12x12.png 12w\" sizes=\"auto, (max-width: 130px) 100vw, 130px\" \/>Literatur<\/div>\n<\/summary>\n<p><span class=\"literatur\"><strong>Die Literatur finden Sie als Studierende*r oder Mitarbeiter*in der Universit\u00e4t zu K\u00f6ln in <a href=\"https:\/\/www.ilias.uni-koeln.de\/ilias\/goto_uk_cat_4168558.html\" target=\"_blank\" rel=\"noopener noreferrer\">ILIAS<\/a>.<\/strong><\/span><\/p>\n<p><span class=\"literatur\">Gesetz \u00fcber die Ausbildung f\u00fcr Lehr\u00e4mter an \u00f6ffentlichen Schulen (Lehrerausbildungsgesetz &#8211; LABG). Vom 12. Mai 2009. Fassung vom 09.03.2022. Online unter: <a href=\"https:\/\/recht.nrw.de\/lmi\/owa\/br_bes_text?sg=1&amp;menu=1&amp;bes_id=12764&amp;aufgehoben=N&amp;anw_nr=2\" target=\"_blank\" rel=\"noopener\">https:\/\/recht.nrw.de\/lmi\/owa\/br_bes_text?sg=1&amp;menu=1&amp;bes_id=12764&amp;aufgehoben=N&amp;anw_nr=2.<\/a> Letzter Aufruf: 27.10.2022<\/span><\/p>\n<\/details>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_grey wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_row wpb_row vc_inner vc_row-fluid vc_custom_1611778571914 vc_row-has-fill\"><div class=\"wpb_column vc_column_container vc_col-sm-2\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div  class=\"wpb_single_image wpb_content_element vc_align_left wpb_content_element\">\n\t\t\n\t\t<figure class=\"wpb_wrapper vc_figure\">\n\t\t\t<div class=\"vc_single_image-wrapper   vc_box_border_grey\"><img loading=\"lazy\" decoding=\"async\" width=\"150\" height=\"150\" src=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/goodluck-150x150.png\" class=\"vc_single_image-img attachment-thumbnail\" alt=\"Icon Kleeblatt\" title=\"goodluck\" srcset=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/goodluck-150x150.png 150w, https:\/\/zfl-lernen.de\/wp-content\/uploads\/goodluck-60x60.png 60w\" sizes=\"auto, (max-width: 150px) 100vw, 150px\" \/><\/div>\n\t\t<\/figure>\n\t<\/div>\n<\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-10\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_empty_space\"   style=\"height: 40px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p><em>Das Team Praxisphasen w\u00fcnscht Ihnen viel Erfolg bei Ihrer Praktikumsplatzsuche.<\/em><\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"Informationen Hier finden Sie wichtige Informationen und rechtliche Rahmenbedingungen f\u00fcr Ihr Berufsfeldpraktikum und das Modul BFP. Bitte lesen Sie die Hinweise aufmerksam durch \u2013 am besten zu Beginn des Semesters, in dem Sie Ihr Begleitseminar belegen. Inhalts\u00fcbersicht \u00dcbersicht \u00fcber den &hellip;","protected":false},"author":4,"featured_media":0,"parent":78654,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[1027,837,1025,1026],"kooperation":[],"licence":[596],"mitwirkende":[],"class_list":["post-78657","online-kurs","type-online-kurs","status-publish","hentry","tag-begleitseminar","tag-bfp","tag-informationen","tag-map","licence-cc-by-sa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Informationen - ZfL Lernen<\/title>\n<meta name=\"description\" content=\"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Informationen - ZfL Lernen\" \/>\n<meta property=\"og:description\" content=\"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-22T13:49:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/\",\"name\":\"Informationen - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ico_hinweis.png\",\"datePublished\":\"2024-06-26T06:17:53+00:00\",\"dateModified\":\"2025-10-22T13:49:05+00:00\",\"description\":\"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ico_hinweis.png\",\"contentUrl\":\"https:\\\/\\\/zfl-lernen.de\\\/wp-content\\\/uploads\\\/ico_hinweis.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/informationen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Praxisphasentransparenz\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"BFP digitaler Begleitkurs\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/praxisphasentransparenz\\\/bfp-digitaler-begleitkurs\\\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Informationen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Informationen - ZfL Lernen","description":"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/","og_locale":"en_US","og_type":"article","og_title":"Informationen - ZfL Lernen","og_description":"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2025-10-22T13:49:05+00:00","og_image":[{"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/","name":"Informationen - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/#primaryimage"},"image":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/#primaryimage"},"thumbnailUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png","datePublished":"2024-06-26T06:17:53+00:00","dateModified":"2025-10-22T13:49:05+00:00","description":"Informationen zum Praktikum zum Begleitseminar und zur MAP im Berufsfeldpraktikum.","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/#primaryimage","url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png","contentUrl":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/ico_hinweis.png"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/informationen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"Praxisphasentransparenz","item":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/"},{"@type":"ListItem","position":4,"name":"BFP digitaler Begleitkurs","item":"https:\/\/zfl-lernen.de\/online-kurs\/praxisphasentransparenz\/bfp-digitaler-begleitkurs\/"},{"@type":"ListItem","position":5,"name":"Informationen"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/78657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/4"}],"up":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/78654"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=78657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=78657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=78657"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=78657"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=78657"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=78657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}