{"id":84897,"date":"2026-01-13T16:55:13","date_gmt":"2026-01-13T15:55:13","guid":{"rendered":"https:\/\/zfl-lernen.de\/?post_type=online-kurs&#038;p=84897"},"modified":"2026-01-13T17:35:31","modified_gmt":"2026-01-13T16:35:31","slug":"pruefungsangst-teil1","status":"publish","type":"online-kurs","link":"https:\/\/zfl-lernen.de\/en\/online-kurs\/pruefungsangst-teil1\/","title":{"rendered":"Pr\u00fcfungsangst-Teil1"},"content":{"rendered":"<div class=\"h5p-iframe-wrapper\"><iframe id=\"h5p-iframe-1519\" class=\"h5p-iframe\" data-content-id=\"1519\" style=\"height:1px\" src=\"about:blank\" frameborder=\"0\" scrolling=\"no\" title=\"Pr\u00fcfungsangst-Einstieg und Formung eines Grundverst\u00e4ndnis\"><\/iframe><\/div>","protected":false},"excerpt":{"rendered":"","protected":false},"author":226,"featured_media":0,"parent":0,"menu_order":0,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"kooperation":[],"licence":[596],"mitwirkende":[],"class_list":["post-84897","online-kurs","type-online-kurs","status-publish","hentry","licence-cc-by-sa"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pr\u00fcfungsangst-Teil1 - ZfL Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/pruefungsangst-teil1\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00fcfungsangst-Teil1 - ZfL Lernen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/online-kurs\/pruefungsangst-teil1\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-13T16:35:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/pruefungsangst-teil1\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/pruefungsangst-teil1\\\/\",\"name\":\"Pr\u00fcfungsangst-Teil1 - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2026-01-13T15:55:13+00:00\",\"dateModified\":\"2026-01-13T16:35:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/pruefungsangst-teil1\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/pruefungsangst-teil1\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/pruefungsangst-teil1\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Online-Kurse\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/online-kurs\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Pr\u00fcfungsangst-Teil1\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00fcfungsangst-Teil1 - ZfL Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/online-kurs\/pruefungsangst-teil1\/","og_locale":"en_US","og_type":"article","og_title":"Pr\u00fcfungsangst-Teil1 - ZfL Lernen","og_url":"https:\/\/zfl-lernen.de\/en\/online-kurs\/pruefungsangst-teil1\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2026-01-13T16:35:31+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/online-kurs\/pruefungsangst-teil1\/","url":"https:\/\/zfl-lernen.de\/online-kurs\/pruefungsangst-teil1\/","name":"Pr\u00fcfungsangst-Teil1 - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2026-01-13T15:55:13+00:00","dateModified":"2026-01-13T16:35:31+00:00","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/online-kurs\/pruefungsangst-teil1\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/online-kurs\/pruefungsangst-teil1\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/online-kurs\/pruefungsangst-teil1\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Online-Kurse","item":"https:\/\/zfl-lernen.de\/online-kurs\/"},{"@type":"ListItem","position":3,"name":"Pr\u00fcfungsangst-Teil1"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs\/84897","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/online-kurs"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/226"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=84897"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=84897"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=84897"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=84897"},{"taxonomy":"licence","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/licence?post=84897"},{"taxonomy":"mitwirkende","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/mitwirkende?post=84897"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}