{"id":84986,"date":"2026-02-26T07:42:55","date_gmt":"2026-02-26T06:42:55","guid":{"rendered":"https:\/\/zfl-lernen.de\/?page_id=84986"},"modified":"2026-02-26T08:51:36","modified_gmt":"2026-02-26T07:51:36","slug":"map-bne","status":"publish","type":"page","link":"https:\/\/zfl-lernen.de\/en\/map-bne\/","title":{"rendered":"Map BNE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div id=\"meta-origin\" data-coolorigin=\"https%3A%2F%2Fcool.sciebo.de%2Fcool%2Fclipboard%3FWOPISrc%3Dhttps%253A%252F%252Funi-koeln.sciebo.de%252Findex.php%252Fapps%252Frichdocuments%252Fwopi%252Ffiles%252F1233892059_oc6aa9d23703%26ServerId%3Ddcdc326f%26ViewId%3D4%26Tag%3D99a2014143be34fa\">\n<p>Diese Game-Map bietet einen \u00dcberblick \u00fcber die einzelnen BNE-Angebote mit direkten Links zu den entsprechenden Seiten.<\/p>\n<\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<div class=\"h5p-iframe-wrapper\"><iframe id=\"h5p-iframe-1573\" class=\"h5p-iframe\" data-content-id=\"1573\" style=\"height:1px\" src=\"about:blank\" frameborder=\"0\" scrolling=\"no\" title=\"Map BNE\"><\/iframe><\/div>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n<\/div>"},"excerpt":{"rendered":"Diese Game-Map bietet einen \u00dcberblick \u00fcber die einzelnen BNE-Angebote mit direkten Links zu den entsprechenden Seiten.","protected":false},"author":226,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"categories":[209,1,717,183,638],"tags":[],"kooperation":[203],"class_list":["post-84986","page","type-page","status-publish","hentry","category-digitale-angebote-des-zfl","category-allgemein","category-bfp-begleitkurs-digital","category-gesundheit-und-schule","category-visionsentwicklung","kooperation-digill"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Map BNE - ZfL Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/map-bne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Map BNE - ZfL Lernen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/map-bne\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/zflkoeln\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-26T07:51:36+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/map-bne\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/map-bne\\\/\",\"name\":\"Map BNE - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"datePublished\":\"2026-02-26T06:42:55+00:00\",\"dateModified\":\"2026-02-26T07:51:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/map-bne\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zfl-lernen.de\\\/map-bne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/map-bne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Map BNE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Map BNE - ZfL Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/map-bne\/","og_locale":"en_US","og_type":"article","og_title":"Map BNE - ZfL Lernen","og_url":"https:\/\/zfl-lernen.de\/en\/map-bne\/","og_site_name":"ZfL Lernen","article_publisher":"https:\/\/www.facebook.com\/zflkoeln","article_modified_time":"2026-02-26T07:51:36+00:00","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zfl-lernen.de\/map-bne\/","url":"https:\/\/zfl-lernen.de\/map-bne\/","name":"Map BNE - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"datePublished":"2026-02-26T06:42:55+00:00","dateModified":"2026-02-26T07:51:36+00:00","breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/map-bne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zfl-lernen.de\/map-bne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/map-bne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Map BNE"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/pages\/84986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/users\/226"}],"replies":[{"embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/comments?post=84986"}],"version-history":[{"count":4,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/pages\/84986\/revisions"}],"predecessor-version":[{"id":84990,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/pages\/84986\/revisions\/84990"}],"wp:attachment":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/media?parent=84986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/categories?post=84986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags?post=84986"},{"taxonomy":"kooperation","embeddable":true,"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/kooperation?post=84986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}