{"id":1134,"count":1,"description":"","link":"https:\/\/zfl-lernen.de\/en\/thema\/hintergrundwissen\/","name":"Hintergrundwissen","slug":"hintergrundwissen","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Hintergrundwissen Archive - ZfL Lernen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zfl-lernen.de\/en\/thema\/hintergrundwissen\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hintergrundwissen Archive - ZfL Lernen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zfl-lernen.de\/en\/thema\/hintergrundwissen\/\" \/>\n<meta property=\"og:site_name\" content=\"ZfL Lernen\" \/>\n<meta property=\"og:image\" content=\"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"161\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Lehrer_innen\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/thema\\\/hintergrundwissen\\\/\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/thema\\\/hintergrundwissen\\\/\",\"name\":\"Hintergrundwissen Archive - ZfL Lernen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/thema\\\/hintergrundwissen\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/thema\\\/hintergrundwissen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/zfl-lernen.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hintergrundwissen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zfl-lernen.de\\\/#website\",\"url\":\"https:\\\/\\\/zfl-lernen.de\\\/\",\"name\":\"ZfL Lernen\",\"description\":\"ZfL Offene Bildungsangebote\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zfl-lernen.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hintergrundwissen Archive - ZfL Lernen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zfl-lernen.de\/en\/thema\/hintergrundwissen\/","og_locale":"en_US","og_type":"article","og_title":"Hintergrundwissen Archive - ZfL Lernen","og_url":"https:\/\/zfl-lernen.de\/en\/thema\/hintergrundwissen\/","og_site_name":"ZfL Lernen","og_image":[{"width":300,"height":161,"url":"https:\/\/zfl-lernen.de\/wp-content\/uploads\/zfl-logo_neu-1.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@Lehrer_innen","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/zfl-lernen.de\/thema\/hintergrundwissen\/","url":"https:\/\/zfl-lernen.de\/thema\/hintergrundwissen\/","name":"Hintergrundwissen Archive - ZfL Lernen","isPartOf":{"@id":"https:\/\/zfl-lernen.de\/#website"},"breadcrumb":{"@id":"https:\/\/zfl-lernen.de\/thema\/hintergrundwissen\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/zfl-lernen.de\/thema\/hintergrundwissen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/zfl-lernen.de\/"},{"@type":"ListItem","position":2,"name":"Hintergrundwissen"}]},{"@type":"WebSite","@id":"https:\/\/zfl-lernen.de\/#website","url":"https:\/\/zfl-lernen.de\/","name":"ZfL Lernen","description":"ZfL Offene Bildungsangebote","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zfl-lernen.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags\/1134","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/posts?tags=1134"},{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/online-kurs?tags=1134"},{"href":"https:\/\/zfl-lernen.de\/en\/wp-json\/wp\/v2\/pages?tags=1134"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}